{"id":230798,"date":"2026-06-14T15:54:20","date_gmt":"2026-06-14T13:54:20","guid":{"rendered":"https:\/\/europeancourt.org\/documents\/interpol\/commission-controle-fichiers\/guide-utilisateur-portail-ccf-demandeurs\/"},"modified":"2026-07-28T13:46:20","modified_gmt":"2026-07-28T13:46:20","slug":"guide-utilisateur-du-portail-ccf-pour-les-demandeurs","status":"publish","type":"page","link":"https:\/\/europeancourt.org\/fr\/documents\/interpol\/commission-de-contr%c3%b4le-des-fichiers-dinterpol\/guide-utilisateur-du-portail-ccf-pour-les-demandeurs\/","title":{"rendered":"Guide utilisateur du portail CCF \u00e0 l\u2019intention des demandeurs"},"content":{"rendered":"<h1 class=\"u-text-center\">Guide d\u2019utilisation du portail de la CCF pour les demandeurs<br\/>Pr\u00e9sentation de requ\u00eates \u00e0 la Commission de contr\u00f4le des fichiers d\u2019INTERPOL (CCF)<\/h1>\n<div class=\"betweendivs\"><a class=\"mybutton blue\" href=\"#\" onclick=\"openall();event.preventDefault();\">Tout d\u00e9plier<\/a> <a class=\"mybutton blue\" href=\"#\" onclick=\"closeall();event.preventDefault();\">Tout replier<\/a><\/div>\n\n<div class=\"su-accordion su-u-trim h-toaccordion includetocloseall\">\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall su-spoiler-closed\" data-anchor=\"important\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h2>Important<\/h2><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Le pr\u00e9sent document ne constitue pas des conseils juridiques ni un avis juridique et est fourni sans pr\u00e9judice de la position que la CCF pourrait adopter sur les questions qui y sont abord\u00e9es. Il vise \u00e0 aider les demandeurs \u00e0 \u00e9tablir et \u00e0 pr\u00e9senter leurs requ\u00eates. Les informations fournies dans le pr\u00e9sent document sont susceptibles d\u2019\u00eatre modifi\u00e9es \u00e0 tout moment et sans pr\u00e9avis.<\/p>\n<p>Le pr\u00e9sent document sera mis \u00e0 jour r\u00e9guli\u00e8rement afin d\u2019y int\u00e9grer les informations compl\u00e9mentaires que la CCF jugera utile d\u2019apporter apr\u00e8s le lancement de son portail.<\/p>\n<p>Il est recommand\u00e9 \u00e0 l\u2019utilisateur de consulter cette page r\u00e9guli\u00e8rement pour s\u2019assurer qu\u2019il s\u2019agit de la derni\u00e8re version en date.<\/p>\n<p><strong>Derni\u00e8re mise \u00e0 jour\u00a0: mars 2026<\/strong><\/p>\n<p><u><strong>\u00c9labor\u00e9 par<\/strong><\/u><strong>\u00a0:<\/strong><br\/>Commission de contr\u00f4le des fichiers d\u2019INTERPOL (CCF)<br\/>200, quai Charles de Gaulle<br\/>69006 Lyon<br\/>France<\/p>\n<\/div><\/div>\n<h2 class=\"su-spoiler-title ec-fake-spoiler-heading\" id=\"rubrique-1\">1. Introduction<\/h2>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall u-indent-1\" data-anchor=\"rubrique-1-1\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>1.1. Remarques pr\u00e9liminaires<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Le pr\u00e9sent Guide du portail de la CCF fournit des conseils sur l\u2019utilisation du portail de la CCF (le \u00ab\u00a0portail\u00a0\u00bb) afin d\u2019aider l\u2019utilisateur \u00e0 pr\u00e9senter une requ\u00eate \u00e0 la Commission de contr\u00f4le des fichiers d\u2019INTERPOL (la \u00ab\u00a0CCF\u00a0\u00bb).<\/p>\n<p>Son principal objectif est d\u2019apporter des pr\u00e9cisions sur certaines questions relatives \u00e0 l\u2019utilisation du portail qui n\u00e9cessitent des explications compl\u00e9mentaires. Le pr\u00e9sent document ne se veut pas un guide exhaustif de chaque question.<\/p>\n<p>L\u2019utilisateur est \u00e9galement tenu de prendre connaissance des conditions d\u2019utilisation et de s\u2019y conformer. Ces conditions d\u00e9finissent les modalit\u00e9s d\u2019acc\u00e8s au portail et ses conditions d\u2019utilisation ainsi que les droits et responsabilit\u00e9s de l\u2019utilisateur et les restrictions applicables.<\/p>\n<p><u>Pr\u00e9cisions terminologiques<\/u>\u00a0: Le terme \u00ab\u00a0demandeur\u00a0\u00bb s\u2019entend de toute personne ou entit\u00e9 qui saisit la CCF d\u2019une requ\u00eate conform\u00e9ment \u00e0 <a href=\"https:\/\/europeancourt.org\/fr\/documents\/interpol\/commission-de-contr%C3%B4le-des-fichiers-dinterpol\/statut\/#article-29\" title=\"Article 29 du Statut de la Commission de contr\u00f4le des fichiers d\u2019INTERPOL\">l\u2019article 29<\/a> ou <a href=\"https:\/\/europeancourt.org\/fr\/documents\/interpol\/commission-de-contr%C3%B4le-des-fichiers-dinterpol\/statut\/#article-42\" title=\"Article 42 du Statut de la Commission de contr\u00f4le des fichiers d\u2019INTERPOL\">42<\/a> du Statut de celle-ci. La requ\u00eate peut \u00eatre pr\u00e9sent\u00e9e directement par la personne ou entit\u00e9 concern\u00e9e, ou par son repr\u00e9sentant habilit\u00e9. Elle peut porter sur des donn\u00e9es qui sont susceptibles d\u2019avoir \u00e9t\u00e9 enregistr\u00e9es dans le Syst\u00e8me d\u2019information d\u2019INTERPOL (SII) et qui concernent la personne ou entit\u00e9 ou ses biens. Le terme \u00ab\u00a0d\u00e9posant\u00a0\u00bb s\u2019entend de la personne ou entit\u00e9 qui d\u00e9pose une requ\u00eate aupr\u00e8s de la CCF, qu\u2019il s\u2019agisse du demandeur lui-m\u00eame ou de son repr\u00e9sentant.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall u-indent-1 su-spoiler-closed\" data-anchor=\"rubrique-1-2\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>1.2. Le portail de la CCF<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Lanc\u00e9 en mars 2026, le portail est la plateforme en ligne s\u00e9curis\u00e9e de la CCF qui permet aux demandeurs et \u00e0 leurs repr\u00e9sentants habilit\u00e9s de cr\u00e9er et de g\u00e9rer leur compte utilisateur, de transmettre des requ\u00eates et des pi\u00e8ces justificatives et de communiquer avec la CCF.<\/p>\n<p>Tous les messages et pi\u00e8ces justificatives \u00e9chang\u00e9s entre les d\u00e9posants et la CCF sont conserv\u00e9s de mani\u00e8re s\u00e9curis\u00e9e et accessibles uniquement depuis le portail. Par cons\u00e9quent, sauf demande exceptionnelle de la CCF, il n\u2019est pas n\u00e9cessaire de communiquer les documents au format papier d\u2019origine. La CCF ne tiendra en effet pas compte des informations ou documents transmis par courrier \u00e9lectronique ou courrier postal, sauf si elle consid\u00e8re que des circonstances exceptionnelles justifient le recours \u00e0 ces modes de transmission, conform\u00e9ment \u00e0 l\u2019<a href=\"https:\/\/europeancourt.org\/fr\/documents\/interpol\/commission-de-contr%C3%B4le-des-fichiers-dinterpol\/r%C3%A8gles-de-fonctionnement\/#article-25\" title=\"Article 25 du R\u00e8gles de fonctionnement de la Commission de contr\u00f4le des fichiers d\u2019INTERPOL\">article 25(2) de ses R\u00e8gles de fonctionnement<\/a>.<\/p>\n<p>Les d\u00e9posants peuvent \u00e9galement consulter le statut de leur(s) requ\u00eate(s) depuis le compte qu\u2019ils ont cr\u00e9\u00e9 sur le portail.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall su-spoiler-closed\" data-anchor=\"rubrique-2\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h2>2. Structure du portail<\/h2><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Le portail a \u00e9t\u00e9 soigneusement con\u00e7u de mani\u00e8re \u00e0 ce que certains champs, signal\u00e9s par un ast\u00e9risque (*), soient obligatoires. Cela permet de s\u2019assurer que les requ\u00eates satisfont aux crit\u00e8res de recevabilit\u00e9 minimums.<\/p>\n<p>Certaines questions sont assorties d\u2019un menu d\u00e9roulant afin de structurer la requ\u00eate. Toutefois, une option \u00ab\u00a0Autre\u00a0\u00bb est toujours propos\u00e9e \u00e0 la fin de la liste d\u00e9roulante pour que le d\u00e9posant puisse choisir une option suppl\u00e9mentaire. Dans ce cas, un champ obligatoire, \u00ab\u00a0Veuillez pr\u00e9ciser\u00a0\u00bb, appara\u00eet qui invite le d\u00e9posant \u00e0 fournir des informations compl\u00e9mentaires.<\/p>\n<p><img decoding=\"async\" alt=\"Ic\u00f4ne de profil du portail de la CCF\" class=\"ec-portal-profile-icon wp-image-231147\" height=\"54\" src=\"https:\/\/europeancourt.org\/wp-content\/uploads\/ccf-portal-user-guide-profile-icon.png\" width=\"53\"\/>Cette ic\u00f4ne, situ\u00e9e en haut \u00e0 droite de chaque page, permet \u00e0 l\u2019utilisateur de se d\u00e9connecter ou de modifier le mot de passe de son compte (via son profil). Les autres \u00e9l\u00e9ments ne sont pas activ\u00e9s.<\/p>\n<\/div><\/div>\n<h2 class=\"su-spoiler-title ec-fake-spoiler-heading\" id=\"rubrique-3\">3. Langues<\/h2>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall u-indent-1 su-spoiler-closed\" data-anchor=\"rubrique-3-1\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>3.1. Langue du portail<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Dans la mesure du possible, les pages du portail sont disponibles en anglais, en arabe, en espagnol et en fran\u00e7ais. Lorsqu\u2019ils transmettent une nouvelle requ\u00eate, les d\u00e9posants peuvent choisir la langue souhait\u00e9e \u00e0 l\u2019aide du menu situ\u00e9 en haut \u00e0 droite de l\u2019\u00e9cran.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall u-indent-1 su-spoiler-closed\" data-anchor=\"rubrique-3-2\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>3.2. Langue des requ\u00eates<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Toutes les requ\u00eates et pi\u00e8ces justificatives doivent \u00eatre pr\u00e9sent\u00e9es en anglais, en arabe, en espagnol ou en fran\u00e7ais, les langues de travail d\u2019INTERPOL, conform\u00e9ment \u00e0 <a href=\"https:\/\/europeancourt.org\/fr\/documents\/interpol\/commission-de-contr%C3%B4le-des-fichiers-dinterpol\/statut\/#article-18\" title=\"Article 18 du Statut de la Commission de contr\u00f4le des fichiers d\u2019INTERPOL\">l\u2019article 18(1) du Statut de la CCF<\/a> et \u00e0 l\u2019<a href=\"https:\/\/europeancourt.org\/fr\/documents\/interpol\/commission-de-contr%C3%B4le-des-fichiers-dinterpol\/r%C3%A8gles-de-fonctionnement\/#article-14\" title=\"Article 14 du R\u00e8gles de fonctionnement de la Commission de contr\u00f4le des fichiers d\u2019INTERPOL\">article 14 de ses R\u00e8gles de fonctionnement<\/a>. Les d\u00e9posants ne peuvent donc utiliser que l\u2019une de ces quatre langues lorsqu\u2019ils saisissent des informations dans le portail. De plus, les annexes r\u00e9dig\u00e9es dans une autre langue doivent \u00eatre traduites dans l\u2019une de ces langues.<\/p>\n<\/div><\/div>\n<h2 class=\"su-spoiler-title ec-fake-spoiler-heading\" id=\"rubrique-4\">4. Rubriques \u00ab\u00a0Request\u00a0\u00bb (requ\u00eate) et \u00ab\u00a0By Whom\u00a0\u00bb (pr\u00e9sent\u00e9e par qui)<\/h2>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall u-indent-1 su-spoiler-closed\" data-anchor=\"rubrique-4-1\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>4.1. Type de requ\u00eate \u00ab Request \u00bb (Requ\u00eate)<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Dans la rubrique \u00ab\u00a0Nouvelle requ\u00eate\u00a0\u00bb du portail, le d\u00e9posant doit d\u2019abord pr\u00e9ciser quel type de requ\u00eate il souhaite pr\u00e9senter. Il peut choisir un des types suivants\u00a0:<\/p>\n<ul class=\"u-list-indent\">\n<li><u>Demande d\u2019acc\u00e8s<\/u>\u00a0: demande d\u2019acc\u00e8s \u00e0 des informations susceptibles d\u2019\u00eatre contenues dans le Syst\u00e8me d\u2019information d\u2019INTERPOL.<\/li>\n<li><u>Demande de rectification\/d\u2019effacement<\/u>\u00a0: demande de rectification ou d\u2019effacement d\u2019informations susceptibles d\u2019\u00eatre contenues dans le Syst\u00e8me d\u2019information d\u2019INTERPOL.<\/li>\n<li><u>Demande de r\u00e9vision<\/u>\u00a0: demande de r\u00e9vision d\u2019une d\u00e9cision de la CCF, conform\u00e9ment \u00e0 <a href=\"https:\/\/europeancourt.org\/fr\/documents\/interpol\/commission-de-contr%C3%B4le-des-fichiers-dinterpol\/statut\/#article-42\" title=\"Article 42 du Statut de la Commission de contr\u00f4le des fichiers d\u2019INTERPOL\">l\u2019article 42 du Statut<\/a> de celle-ci.<\/li>\n<\/ul>\n<p>Une seule option peut \u00eatre choisie. Si le d\u00e9posant souhaite pr\u00e9senter plusieurs types de requ\u00eates (demande d\u2019acc\u00e8s + demande de rectification ou d\u2019effacement, ou demande d\u2019acc\u00e8s + demande de r\u00e9vision), il doit les pr\u00e9senter s\u00e9par\u00e9ment. Lors de la transmission d\u2019une requ\u00eate, il est possible de cr\u00e9er un lien entre celle-ci et des requ\u00eates existantes (voir la rubrique \u00ab\u00a0Lien\u00a0\u00bb).<\/p>\n<p>Si le demandeur souhaite pr\u00e9senter une requ\u00eate ult\u00e9rieure, il doit transmettre une nouvelle requ\u00eate compl\u00e8te.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall u-indent-1 su-spoiler-closed\" data-anchor=\"rubrique-4-2\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>4.2. Personne ou entit\u00e9 qui pr\u00e9sente la requ\u00eate \u00ab By Whom \u00bb (Pr\u00e9sent\u00e9e par qui)<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Dans cette rubrique, le d\u00e9posant est invit\u00e9 \u00e0 pr\u00e9ciser qui pr\u00e9sente la requ\u00eate au nom du demandeur. Le demandeur peut pr\u00e9senter la requ\u00eate lui-m\u00eame ou par l\u2019interm\u00e9diaire d\u2019un mandataire habilit\u00e9. Le mandataire habilit\u00e9 peut \u00eatre toute personne d\u00e9sign\u00e9e par le demandeur en vertu d\u2019un pouvoir, et n\u2019est pas n\u00e9cessairement un avocat\u00a0: il peut s\u2019agir par exemple d\u2019un membre de la famille, d\u2019un(e) ami(e) ou d\u2019une ONG ou association.<\/p>\n<p>Dans cette rubrique, le d\u00e9posant est \u00e9galement invit\u00e9 \u00e0 pr\u00e9ciser si la requ\u00eate porte sur des donn\u00e9es concernant une personne ou une entit\u00e9.<\/p>\n<p>Si le d\u00e9posant souhaite pr\u00e9senter des requ\u00eates li\u00e9es concernant plusieurs personnes (m\u00eame affaire criminelle, parent\/enfant, etc.), une requ\u00eate distincte doit \u00eatre transmise pour chacune de ces personnes. Lors de la proc\u00e9dure permettant de transmettre une demande d\u2019acc\u00e8s ou de rectification\/d\u2019effacement, une rubrique permet de fournir des informations sur des requ\u00eates li\u00e9es (\u00ab\u00a0Lien\u00a0\u00bb).<\/p>\n<p><u>N<\/u>.<u>B<\/u>.\u00a0: Lorsqu\u2019un parent repr\u00e9sente son enfant \u00e2g\u00e9 de plus de 18 ans, il convient de choisir \u00ab\u00a0Je suis le repr\u00e9sentant l\u00e9gal du demandeur\u00a0\u00bb et non \u00ab\u00a0Je suis le parent ou le tuteur du demandeur\u00a0\u00bb.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall u-indent-1 su-spoiler-closed\" data-anchor=\"rubrique-4-3\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>4.3. Autres rubriques \u00e0 remplir<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Selon les options choisies dans les rubriques \u00ab\u00a0Requ\u00eate\u00a0\u00bb et \u00ab\u00a0Pr\u00e9sent\u00e9e par qui\u00a0\u00bb, le portail d\u00e9terminera les autres rubriques que le d\u00e9posant doit remplir. Par exemple, la rubrique \u00ab\u00a0Representative\u00a0\u00bb (Mandataire) dispara\u00eetra si le d\u00e9posant indique qu\u2019il est lui-m\u00eame le demandeur.<\/p>\n<p>Les rubriques ci-apr\u00e8s appara\u00eetront donc uniquement si elles sont applicables \u00e0 la requ\u00eate.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall su-spoiler-closed\" data-anchor=\"rubrique-5\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h2>5. Rubrique \u00ab Parent\/Guardian \u00bb (parent\/tuteur)<\/h2><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Cette rubrique doit \u00eatre remplie lorsque le demandeur est repr\u00e9sent\u00e9 directement par un parent ou un tuteur, ou lorsqu\u2019un parent ou un tuteur a sign\u00e9 un pouvoir d\u00e9signant un repr\u00e9sentant l\u00e9gal pour repr\u00e9senter le demandeur.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall u-indent-1 su-spoiler-closed\" data-anchor=\"rubrique-5-1\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>5.1. Parent<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Cette rubrique concerne uniquement les enfants mineurs \u00e2g\u00e9s de moins de 18 ans. Comme indiqu\u00e9 plus haut, si l\u2019enfant est \u00e2g\u00e9 de plus de 18 ans, il convient de choisir \u00ab\u00a0Je suis le repr\u00e9sentant l\u00e9gal du demandeur\u00a0\u00bb dans la rubrique \u00ab\u00a0Pr\u00e9sent\u00e9e par qui\u00a0\u00bb.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall u-indent-1 su-spoiler-closed\" data-anchor=\"rubrique-5-2\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>5.2. Tuteur<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Un tuteur l\u00e9gal peut pr\u00e9senter une requ\u00eate au nom d\u2019un adulte ou d\u2019un mineur \u00e2g\u00e9 de moins de 18 ans.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall su-spoiler-closed\" data-anchor=\"rubrique-6\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h2>6. Rubrique \u00ab Representative \u00bb (mandataire)<\/h2><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Cette rubrique doit \u00eatre remplie lorsque le demandeur est repr\u00e9sent\u00e9 par un mandataire, lequel peut \u00eatre un avocat, un membre de la famille, une ONG ou toute autre personne d\u00e9sign\u00e9e par le demandeur en vertu d\u2019un pouvoir.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall u-indent-1 su-spoiler-closed\" data-anchor=\"rubrique-6-1\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>6.1. Requ\u00eate initiale<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p><u>Mod\u00e8le de pouvoir<\/u>\u00a0: Ce mod\u00e8le permet au demandeur de d\u00e9signer son mandataire principal et jusqu\u2019\u00e0 deux personnes de contact au sein de l\u2019entit\u00e9 qui le repr\u00e9sente, laquelle peut \u00eatre un cabinet d\u2019avocats ou une ONG par exemple. La CCF pourra ainsi envoyer les messages concernant la requ\u00eate tout au plus \u00e0 trois membres de la m\u00eame entit\u00e9. Le demandeur peut utiliser ce mod\u00e8le de pouvoir ou son propre mod\u00e8le. Le pouvoir doit \u00eatre sign\u00e9 par le demandeur (un pouvoir sign\u00e9 par un avocat qui en d\u00e9signe un autre ne sera pas accept\u00e9 par la CCF).<\/p>\n<p><u>Date d\u2019expiration du pouvoir<\/u>\u00a0: Si le pouvoir ne comporte pas de date d\u2019expiration, la CCF consid\u00e9rera qu\u2019il est valable pendant deux ans \u00e0 compter de la date de sa signature par le demandeur.<\/p>\n<p><u>Votre r\u00e9f\u00e9rence<\/u>\u00a0: Si le mandataire dispose d\u2019un num\u00e9ro de r\u00e9f\u00e9rence de dossier pour la requ\u00eate, il peut l\u2019indiquer dans ce champ. Cette r\u00e9f\u00e9rence sera rappel\u00e9e dans toute correspondance de la CCF.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall u-indent-1 su-spoiler-closed\" data-anchor=\"rubrique-6-2\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>6.2. Le demandeur souhaite changer de mandataire<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Si le demandeur souhaite changer de mandataire pendant l\u2019examen d\u2019une requ\u00eate, le nouveau mandataire doit pr\u00e9senter une nouvelle requ\u00eate via le portail, en fournissant un nouveau pouvoir sign\u00e9 par le demandeur. D\u00e8s lors que les conditions de recevabilit\u00e9 sont remplies, le nouveau mandataire deviendra automatiquement le seul point de contact avec la CCF en ce qui concerne la requ\u00eate.<\/p>\n<p>Le nouveau mandataire devra indiquer clairement si la CCF doit tenir compte de la requ\u00eate pr\u00e9sent\u00e9e par l\u2019ancien ou les anciens mandataire(s), ou si sa propre requ\u00eate doit \u00eatre consid\u00e9r\u00e9e comme une nouvelle requ\u00eate qui annule et remplace les requ\u00eates pr\u00e9c\u00e9dentes. De plus, et d\u00e8s lors que les crit\u00e8res de recevabilit\u00e9 sont remplis, le nouveau mandataire pourra demander que l\u2019examen de la requ\u00eate existante soit suspendu pendant qu\u2019il \u00e9tablit la nouvelle requ\u00eate.<\/p>\n<p>Si un demandeur qui avait d\u00e9j\u00e0 saisi la CCF par l\u2019interm\u00e9diaire d\u2019un mandataire pr\u00e9sente une requ\u00eate directement \u00e0 la CCF, celle-ci y verra une indication de sa part que le demandeur est le seul point de contact pour la suite de la proc\u00e9dure et elle en informera comme il se doit le mandataire pr\u00e9c\u00e9demment d\u00e9sign\u00e9.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall su-spoiler-closed\" data-anchor=\"rubrique-7\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h2>7. Rubrique \u00ab Applicant \u00bb (demandeur)<\/h2><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Cette rubrique doit \u00eatre remplie lorsque le demandeur est une personne.<\/p>\n<p><u>Nom \u2013 graphie d\u2019origine (alphabet non romain)<\/u>\u00a0: Lorsque le nom du demandeur est \u00e9crit, sur son document d\u2019identit\u00e9, dans un alphabet autre que l\u2019alphabet romain, le d\u00e9posant est invit\u00e9 \u00e0 saisir le nom dans sa graphie d\u2019origine. Si le nom s\u2019\u00e9crit en caract\u00e8res romains dans la langue d\u2019origine, alors ce champ doit \u00eatre laiss\u00e9 vierge. Le libell\u00e9 dans l\u2019alphabet d\u2019origine sera utilis\u00e9 pour permettre un traitement plus pr\u00e9cis de la requ\u00eate, en tenant compte des diff\u00e9rentes translitt\u00e9rations possibles.<\/p>\n<p><u>Date de naissance<\/u>\u00a0: La date de naissance compl\u00e8te, telle qu\u2019elle figure sur le document d\u2019identit\u00e9 du demandeur, doit toujours \u00eatre indiqu\u00e9e, mais il arrive parfois que certains documents d\u2019identit\u00e9 n\u2019indiquent que l\u2019ann\u00e9e de naissance. Dans ces rares cas, le d\u00e9posant doit inscrire le 1er janvier de l\u2019ann\u00e9e en question dans ce champ.<\/p>\n<p><u>Nationalit\u00e9<\/u>\u00a0: Si le demandeur est actuellement apatride, il convient de choisir l\u2019option \u00ab\u00a0Autre\u00a0\u00bb dans \u00ab\u00a0Nationalit\u00e9 1\u00a0\u00bb et d\u2019indiquer \u00ab\u00a0Apatride\u00a0\u00bb dans le champ \u00ab\u00a0Veuillez pr\u00e9ciser\u00a0\u00bb. Des informations compl\u00e9mentaires sur la situation du demandeur doivent \u00eatre fournies dans la rubrique \u00ab\u00a0D\u00e9tails de la requ\u00eate\u00a0\u00bb.<\/p>\n<p><u>Document d\u2019identit\u00e9<\/u>\u00a0: Il est obligatoire de fournir une copie de l\u2019un des documents d\u2019identit\u00e9 du demandeur, mais un deuxi\u00e8me document peut \u00eatre ajout\u00e9 dans cette rubrique en cochant la case \u00ab\u00a0Document d\u2019identit\u00e9 2\u00a0\u00bb. Ce document officiel doit comporter tous les \u00e9l\u00e9ments n\u00e9cessaires \u00e0 l\u2019identification de la personne (au moins ses nom et pr\u00e9nom, sa date de naissance et sa photographie) et ne doit pas comporter de ratures, mentions effac\u00e9es, caract\u00e8res illisibles, etc. Dans la mesure o\u00f9 certaines de ces informations peuvent figurer au verso du document, il est possible de t\u00e9l\u00e9verser deux fichiers, un pour le recto et un pour le verso.<\/p>\n<p>Si le demandeur ne poss\u00e8de aucun des types de documents indiqu\u00e9s, le d\u00e9posant est invit\u00e9 \u00e0 transmettre, en y joignant les justificatifs \u00e9ventuellement n\u00e9cessaires, tout autre document d\u2019identit\u00e9 ou toute d\u00e9claration expliquant pourquoi un document d\u2019identit\u00e9 officiel ne peut \u00eatre fourni. Si aucun num\u00e9ro de document ne peut \u00eatre fourni, il convient d\u2019indiquer \u00ab\u00a0sans objet\u00a0\u00bb dans ce champ et de fournir des informations compl\u00e9mentaires dans la rubrique \u00ab\u00a0D\u00e9tails de la requ\u00eate\u00a0\u00bb, un peu plus loin dans le formulaire. <u>Attention<\/u>\u00a0: Si aucun document d\u2019identit\u00e9 valable n\u2019est fourni ou si aucune explication n\u2019est donn\u00e9e quant \u00e0 l\u2019absence de document, la requ\u00eate sera consid\u00e9r\u00e9e comme irrecevable.<\/p>\n<p><u>Num\u00e9ro du document<\/u>\u00a0: Il s\u2019agit du num\u00e9ro du document \u00e0 proprement parler et non du num\u00e9ro d\u2019identification fiscale ou de s\u00e9curit\u00e9 sociale permanent du demandeur, lequel peut \u00e9galement appara\u00eetre sur le document d\u2019identit\u00e9 dans certains pays.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall su-spoiler-closed\" data-anchor=\"rubrique-8\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h2>8. Rubrique \u00ab Entity \u00bb (entit\u00e9)<\/h2><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Cette rubrique doit \u00eatre remplie lorsque le demandeur est une entit\u00e9, laquelle peut par exemple \u00eatre le propri\u00e9taire du v\u00e9hicule ou autre bien concern\u00e9 par la requ\u00eate.<\/p>\n<p><u>Extrait du registre du commerce \/acte constitutif de l\u2019entit\u00e9<\/u>\u00a0: Ce document doit \u00eatre fourni dans tous les cas et doit, le cas \u00e9ch\u00e9ant, \u00eatre traduit dans l\u2019une des langues officielles d\u2019INTERPOL.<\/p>\n<p><u>Signataire de la soci\u00e9t\u00e9<\/u>\u00a0: Il s\u2019agit d\u2019une personne qui est officiellement habilit\u00e9e \u00e0 signer des documents au nom de la soci\u00e9t\u00e9.<\/p>\n<p><u>Document attestant de l\u2019habilitation du signataire \u00e0 repr\u00e9senter l\u2019entit\u00e9<\/u>\u00a0: Un document officiel de la soci\u00e9t\u00e9 doit \u00eatre fourni qui confirme l\u2019habilitation du signataire \u00e0 signer au nom de l\u2019entit\u00e9. Il peut s\u2019agir par exemple de l\u2019acte constitutif, des statuts de la soci\u00e9t\u00e9 ou d\u2019une r\u00e9solution du conseil d\u2019administration.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall su-spoiler-closed\" data-anchor=\"rubrique-9\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h2>9. Rubrique \u00ab Data \u00bb (donn\u00e9es)<\/h2><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Dans cette rubrique, le d\u00e9posant est invit\u00e9 \u00e0 confirmer le type de donn\u00e9es qui fait l\u2019objet de la requ\u00eate. Il est possible de choisir une ou plusieurs des cinq options suivantes\u00a0:<\/p>\n<p><u>Donn\u00e9es nominatives<\/u>\u00a0: La requ\u00eate porte sur des donn\u00e9es relatives au demandeur (qu\u2019il s\u2019agisse d\u2019une personne ou d\u2019une entit\u00e9), plus pr\u00e9cis\u00e9ment sur des donn\u00e9es le concernant qui sont susceptibles d\u2019avoir \u00e9t\u00e9 enregistr\u00e9es dans le Syst\u00e8me d\u2019information d\u2019INTERPOL. Cette option est s\u00e9lectionn\u00e9e par d\u00e9faut et ne peut \u00eatre modifi\u00e9e.<\/p>\n<p><u>Donn\u00e9es sur un v\u00e9hicule<\/u>\u00a0: La requ\u00eate porte sur des donn\u00e9es concernant un v\u00e9hicule appartenant au demandeur qui peuvent avoir \u00e9t\u00e9 enregistr\u00e9es dans la base de donn\u00e9es d\u2019INTERPOL sur les v\u00e9hicules vol\u00e9s.<\/p>\n<ul class=\"u-list-indent\">\n<li>Le num\u00e9ro d\u2019identification du v\u00e9hicule (num\u00e9ro VIN) est un num\u00e9ro de s\u00e9rie, presque universellement reconnu par l\u2019industrie automobile, qui permet d\u2019identifier de mani\u00e8re unique un v\u00e9hicule. Ce num\u00e9ro figure sur le certificat d\u2019immatriculation du v\u00e9hicule. Les num\u00e9ros VIN actuels comportent 17 caract\u00e8res et ne peuvent contenir les lettres I, O ni Q. Le d\u00e9posant doit \u00eatre attentif lorsqu\u2019il saisit le num\u00e9ro VIN afin d\u2019\u00e9viter que ces trois lettres puissent \u00eatre confondues avec d\u2019autres chiffres figurant dans ce num\u00e9ro tels que 1 (un) et 0 (z\u00e9ro).<\/li>\n<li>Si le demandeur ne poss\u00e8de pas de document d\u00e9livr\u00e9 par l\u2019\u00c9tat confirmant qu\u2019il est actuellement le propri\u00e9taire officiel du v\u00e9hicule, le d\u00e9posant doit transmettre des documents qui l\u2019attestent. Des explications doivent \u00eatre fournies \u00e0 ce sujet dans la rubrique \u00ab\u00a0D\u00e9tails de la requ\u00eate\u00a0\u00bb, un peu plus loin dans le formulaire.<\/li>\n<\/ul>\n<p><u>Document de voyage<\/u>\u00a0: La requ\u00eate porte sur des donn\u00e9es concernant le document de voyage du demandeur qui peuvent avoir \u00e9t\u00e9 enregistr\u00e9es dans la base de donn\u00e9es SLTD d\u2019INTERPOL.<\/p>\n<p><u>Donn\u00e9es sur un navire<\/u>\u00a0: La requ\u00eate porte sur des donn\u00e9es concernant un navire appartenant au demandeur qui peuvent avoir \u00e9t\u00e9 enregistr\u00e9es dans les bases de donn\u00e9es d\u2019INTERPOL.<\/p>\n<p><u>Donn\u00e9es sur une \u0153uvre d\u2019art<\/u>\u00a0: La requ\u00eate porte sur des donn\u00e9es concernant une \u0153uvre d\u2019art appartenant au demandeur qui peuvent avoir \u00e9t\u00e9 enregistr\u00e9es dans la base de donn\u00e9es d\u2019INTERPOL sur les \u0153uvres d\u2019art.<\/p>\n<p><strong>Important<\/strong>\u00a0: Ind\u00e9pendamment de l\u2019option ou des options choisies ci-dessus, dans le cadre de l\u2019examen approfondi de la requ\u00eate, l\u2019identit\u00e9 du propri\u00e9taire de tout v\u00e9hicule, document de voyage, navire ou \u0153uvre d\u2019art mentionn\u00e9(e) dans la requ\u00eate sera v\u00e9rifi\u00e9e afin de d\u00e9terminer si des donn\u00e9es le concernant sont en cours de traitement dans le Syst\u00e8me d\u2019information d\u2019INTERPOL (SII).<\/p>\n<\/div><\/div>\n<h2 class=\"su-spoiler-title ec-fake-spoiler-heading\" id=\"rubrique-10\">10. Rubrique \u00ab\u00a0Request Detail\u00a0\u00bb (d\u00e9tails de la requ\u00eate)<\/h2>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall u-indent-1 su-spoiler-closed\" data-anchor=\"rubrique-10-1\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>10.1. Demande d\u2019acc\u00e8s<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Aucune information compl\u00e9mentaire n\u2019est requise pour une demande d\u2019acc\u00e8s. Il n\u2019est donc pas n\u00e9cessaire d\u2019y joindre une lettre d\u2019accompagnement. Des compl\u00e9ments d\u2019information peuvent toutefois \u00eatre fournis dans les champs structur\u00e9s pr\u00e9vus \u00e0 cet effet.<\/p>\n<p>En particulier, avant de transmettre la requ\u00eate, le d\u00e9posant est invit\u00e9 \u00e0 v\u00e9rifier si des notices rouges ou des notices jaunes concernant le demandeur ont \u00e9t\u00e9 publi\u00e9es sur le site Web d\u2019INTERPOL et, si tel est le cas, \u00e0 l\u2019indiquer dans cette rubrique. Il est \u00e0 noter \u00e0 ce propos que les notices rouges sont g\u00e9n\u00e9ralement r\u00e9serv\u00e9es \u00e0 l\u2019usage des services charg\u00e9s de l\u2019application de la loi et ne sont donc pas publi\u00e9es sur le site Web d\u2019INTERPOL.<\/p>\n<p><u>De quel(s) pays\/de quelle entit\u00e9<\/u>\u00a0: Le d\u00e9posant est invit\u00e9 \u00e0 fournir toute information ou tout document en sa possession indiquant express\u00e9ment que des donn\u00e9es pourraient avoir \u00e9t\u00e9 enregistr\u00e9es dans le Syst\u00e8me d\u2019information d\u2019INTERPOL. Cela pourra faciliter le traitement de la requ\u00eate. Selon <a href=\"https:\/\/europeancourt.org\/fr\/documents\/interpol\/commission-de-contr%C3%B4le-des-fichiers-dinterpol\/statut\/#article-35\" title=\"Article 35 du Statut de la Commission de contr\u00f4le des fichiers d\u2019INTERPOL\">l\u2019article 35(2) de son Statut<\/a>, la CCF doit consulter tout pays ou toute entit\u00e9 potentiellement concern\u00e9(e) par la requ\u00eate avant de divulguer des donn\u00e9es susceptibles d\u2019avoir \u00e9t\u00e9 enregistr\u00e9es dans le Syst\u00e8me d\u2019information d\u2019INTERPOL.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall u-indent-1 su-spoiler-closed\" data-anchor=\"rubrique-10-2\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>10.2. Demande de rectification\/d\u2019effacement<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Dans cette rubrique, il est obligatoire d\u2019indiquer l\u2019article ou les articles de la r\u00e9glementation d\u2019INTERPOL qui auraient \u00e9t\u00e9 enfreints et qui constituent le fondement juridique de la demande de rectification ou d\u2019effacement de donn\u00e9es.<\/p>\n<p>Si le demandeur n\u2019a pas pr\u00e9sent\u00e9 de demande d\u2019acc\u00e8s, le d\u00e9posant est invit\u00e9 \u00e0 v\u00e9rifier si des notices rouges ou des notices jaunes concernant le demandeur ont \u00e9t\u00e9 publi\u00e9es sur le site Web d\u2019INTERPOL et, si tel est le cas, \u00e0 l\u2019indiquer. Il est \u00e0 noter \u00e0 ce propos que les notices rouges sont g\u00e9n\u00e9ralement r\u00e9serv\u00e9es \u00e0 l\u2019usage des services charg\u00e9s de l\u2019application de la loi et ne sont donc pas publi\u00e9es sur le site Web d\u2019INTERPOL.<\/p>\n<p><u>Statut de protection<\/u>\u00a0: Cette case doit \u00eatre coch\u00e9e si le demandeur b\u00e9n\u00e9ficie d\u2019un statut qui le prot\u00e8ge contre le refoulement vers son pays d\u2019origine (r\u00e9fugi\u00e9 ou demandeur d\u2019asile). Ce crit\u00e8re peut en effet avoir une incidence sur l\u2019examen de la requ\u00eate au regard de la r\u00e9solution d\u2019INTERPOL concernant les r\u00e9fugi\u00e9s, accessible sur son site Web. Si le demandeur b\u00e9n\u00e9ficie d\u2019un statut d\u2019immigration ou d\u00e9tient un titre de s\u00e9jour qui ne le prot\u00e8ge pas contre le refoulement, cette rubrique ne doit pas \u00eatre remplie puisqu\u2019elle est r\u00e9serv\u00e9e aux personnes qui ont demand\u00e9 \u00e0 b\u00e9n\u00e9ficier d\u2019une protection internationale.<\/p>\n<p><u>Arguments<\/u>\u00a0: Le d\u00e9posant doit exposer les arguments sur lesquels se fonde la demande dans un document ne d\u00e9passant pas dix pages, conform\u00e9ment \u00e0 l\u2019<a href=\"https:\/\/europeancourt.org\/fr\/documents\/interpol\/commission-de-contr%C3%B4le-des-fichiers-dinterpol\/r%C3%A8gles-de-fonctionnement\/#article-30\" title=\"Article 30 du R\u00e8gles de fonctionnement de la Commission de contr\u00f4le des fichiers d\u2019INTERPOL\">article 30(8) des R\u00e8gles de fonctionnement de la CCF<\/a>. Le respect de cette limite est essentiel pour que la CCF puisse traiter les requ\u00eates efficacement.<\/p>\n<p>Cet expos\u00e9 succinct des arguments doit comporter les \u00e9l\u00e9ments suivants\u00a0:<\/p>\n<p class=\"u-indent-1\">i) le contexte factuel de la requ\u00eate\u00a0;<\/p>\n<p class=\"u-indent-1\">ii) les arguments juridiques, pr\u00e9sent\u00e9s de mani\u00e8re organis\u00e9e, invoqu\u00e9s \u00e0 l\u2019appui de l\u2019affirmation selon laquelle un ou plusieurs articles de la r\u00e9glementation d\u2019INTERPOL auraient \u00e9t\u00e9 enfreints\u00a0;<\/p>\n<p class=\"u-indent-1\">iii) un expos\u00e9 clair de l\u2019objet de la requ\u00eate, au d\u00e9but ou \u00e0 la fin du document.<\/p>\n<p>Le d\u00e9posant peut \u00e9galement fournir les \u00e9l\u00e9ments suivants\u00a0:<\/p>\n<p class=\"u-indent-1\">i) toute information compl\u00e9mentaire concernant le demandeur susceptible d\u2019\u00eatre utile en vue de l\u2019examen de la requ\u00eate (fonctions ant\u00e9rieures et actuelles, proc\u00e9dures judiciaires en cours, etc.)\u00a0;<\/p>\n<p class=\"u-indent-1\">ii) renvois aux annexes \u00e9ventuelles (voir ci-apr\u00e8s)\u00a0;<\/p>\n<p class=\"u-indent-1\">iii) informations compl\u00e9mentaires sur des requ\u00eates li\u00e9es pr\u00e9sent\u00e9es \u00e0 la CCF\u00a0;<\/p>\n<p class=\"u-indent-1\">iv) Restrictions\u00a0: Conform\u00e9ment \u00e0 <a href=\"https:\/\/europeancourt.org\/fr\/documents\/interpol\/commission-de-contr%C3%B4le-des-fichiers-dinterpol\/statut\/#article-33\" title=\"Article 33 du Statut de la Commission de contr\u00f4le des fichiers d\u2019INTERPOL\">l\u2019article 33 du Statut de la CCF<\/a>, les informations contenues dans toutes les requ\u00eates sont communiqu\u00e9es au Secr\u00e9tariat g\u00e9n\u00e9ral d\u2019INTERPOL. Par cons\u00e9quent, le demandeur ne peut demander que des restrictions soient appliqu\u00e9es aux informations transmises \u00e0 ce dernier. Si le demandeur souhaite que des restrictions soient appliqu\u00e9es \u00e0 l\u2019\u00e9gard d\u2019une source des donn\u00e9es, ces restrictions doivent \u00eatre clairement indiqu\u00e9es dans une rubrique sp\u00e9cifique de l\u2019expos\u00e9 des arguments.<\/p>\n<p class=\"u-indent-1\">v) toute autre information relative \u00e0 la requ\u00eate, ou \u00e0 la transmission de celle-ci, qu\u2019il n\u2019\u00e9tait pas possible de communiquer ailleurs dans la proc\u00e9dure.<\/p>\n<p><u>Annexes<\/u>\u00a0: Le d\u00e9posant peut transmettre <u>jusqu\u2019\u00e0 20 annexes<\/u>, lesquelles doivent \u00eatre clairement r\u00e9pertori\u00e9es dans le document contenant l\u2019expos\u00e9 des arguments, conform\u00e9ment \u00e0 l\u2019article 30(8) des R\u00e8gles de fonctionnement de la CCF. Le menu d\u00e9roulant dans le champ \u00ab\u00a0Type de document\u00a0\u00bb contient des exemples des types de documents qui peuvent \u00eatre transmis, mais cette liste n\u2019est pas exhaustive et tout document r\u00e9ellement pertinent aux fins de la requ\u00eate peut \u00eatre joint.<\/p>\n<p>Si la requ\u00eate renvoie \u00e0 des informations publi\u00e9es sur un site Web en libre acc\u00e8s, le ou les liens (URL) renvoyant vers la ou les pages concern\u00e9e(s) doi(ven)t \u00eatre fourni(s) dans ce document (en mettant en \u00e9vidence les informations pertinentes) afin de permettre \u00e0 la CCF d\u2019acc\u00e9der \u00e0 ce contenu, mais la version PDF ne doit pas \u00eatre communiqu\u00e9e dans les annexes. Toutefois, si les pages ou articles en question sont payants ou n\u00e9cessitent de se connecter \u00e0 un compte utilisateur (gratuit ou non), ils doivent \u00eatre communiqu\u00e9s sous forme de documents PDF dans les annexes (en mettant en \u00e9vidence les informations pertinentes).<\/p>\n<p>La CCF demande que les annexes et les fichiers y aff\u00e9rents soient clairement nomm\u00e9s, en s\u2019inspirant de l\u2019exemple suivant\u00a0:<\/p>\n<p class=\"u-text-center\"><img decoding=\"async\" alt=\"Exemple d\u2019annexes dans le portail de la CCF\" class=\"aligncenter size-full wp-image-231148\" height=\"614\" src=\"https:\/\/europeancourt.org\/wp-content\/uploads\/ccf-portal-user-guide-appendices-example.png\" width=\"1007\" srcset=\"https:\/\/europeancourt.org\/wp-content\/uploads\/ccf-portal-user-guide-appendices-example.png 1007w, https:\/\/europeancourt.org\/wp-content\/uploads\/ccf-portal-user-guide-appendices-example-400x244.png 400w, https:\/\/europeancourt.org\/wp-content\/uploads\/ccf-portal-user-guide-appendices-example-800x488.png 800w, https:\/\/europeancourt.org\/wp-content\/uploads\/ccf-portal-user-guide-appendices-example-768x468.png 768w\" sizes=\"(max-width: 1007px) 100vw, 1007px\" \/><\/p>\n<p>Les documents vid\u00e9o et audio ne sont pas pris en compte lors de l\u2019examen d\u2019une requ\u00eate. La proc\u00e9dure devant la CCF est une proc\u00e9dure \u00e9crite et par cons\u00e9quent, seules les transcriptions des extraits pertinents peuvent \u00eatre prises en consid\u00e9ration.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall u-indent-1 su-spoiler-closed\" data-anchor=\"rubrique-10-3\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>10.3. Demande de r\u00e9vision<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Dans cette rubrique, doit \u00eatre communiqu\u00e9 \u00e0 la CCF au moins un fait nouveau qui aurait pu conduire la Chambre des requ\u00eates \u00e0 une conclusion diff\u00e9rente si ce fait avait \u00e9t\u00e9 connu au moment de l\u2019examen de la demande de rectification ou d\u2019effacement d\u2019origine. La Chambre des requ\u00eates est la chambre de la CCF qui examine les demandes de rectification ou d\u2019effacement de donn\u00e9es trait\u00e9es dans le Syst\u00e8me d\u2019information d\u2019INTERPOL et se prononce sur ces demandes.<\/p>\n<p>\u00c0 ce stade de la proc\u00e9dure, le d\u00e9posant peut joindre un seul document\u00a0: un r\u00e9sum\u00e9 de deux pages d\u00e9crivant succinctement le ou les faits nouveaux.<\/p>\n<p>Une fois que la CCF a proc\u00e9d\u00e9 \u00e0 l\u2019examen initial du ou des faits nouveaux communiqu\u00e9s, elle peut demander des documents compl\u00e9mentaires au d\u00e9posant. \u00c0 ce stade, mais pas avant, le d\u00e9posant peut transmettre un expos\u00e9 de ses arguments dans un document ne d\u00e9passant pas dix pages, conform\u00e9ment \u00e0 l\u2019<a href=\"https:\/\/europeancourt.org\/fr\/documents\/interpol\/commission-de-contr%C3%B4le-des-fichiers-dinterpol\/r%C3%A8gles-de-fonctionnement\/#article-30\" title=\"Article 30 du R\u00e8gles de fonctionnement de la Commission de contr\u00f4le des fichiers d\u2019INTERPOL\">article 30(8) des R\u00e8gles de fonctionnement de la CCF<\/a>. Le respect de cette limite est essentiel pour que la CCF puisse traiter les requ\u00eates efficacement.<\/p>\n<p>Aux termes de <a href=\"https:\/\/europeancourt.org\/fr\/documents\/interpol\/commission-de-contr%C3%B4le-des-fichiers-dinterpol\/statut\/#article-42\" title=\"Article 42 du Statut de la Commission de contr\u00f4le des fichiers d\u2019INTERPOL\">l\u2019article 42(2) du Statut de la CCF<\/a>, la demande de r\u00e9vision doit \u00eatre pr\u00e9sent\u00e9e dans les six mois \u00e0 compter de la d\u00e9couverte du fait en question.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall su-spoiler-closed\" data-anchor=\"rubrique-11\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h2>11. Rubrique \u00ab Link \u00bb (lien)<\/h2><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Cette rubrique permet au d\u00e9posant de cr\u00e9er un lien entre la requ\u00eate en cours d\u2019\u00e9laboration et une autre requ\u00eate. Diff\u00e9rentes raisons peuvent amener \u00e0 relier des requ\u00eates entre elles, dont celles-ci\u00a0:<\/p>\n<ul class=\"u-list-indent\">\n<li>Les requ\u00eates li\u00e9es concernent le m\u00eame demandeur.<\/li>\n<li>Les requ\u00eates li\u00e9es concernent la m\u00eame affaire criminelle.<\/li>\n<li>Les requ\u00eates li\u00e9es concernent des membres d\u2019une m\u00eame famille (par exemple, un parent et son enfant).<\/li>\n<\/ul>\n<p>Le d\u00e9posant souhaitera peut-\u00eatre transmettre une ou plusieurs requ\u00eates li\u00e9es en m\u00eame temps, par exemple une requ\u00eate concernant un parent et son enfant. Dans ce cas, lors de la transmission de la premi\u00e8re requ\u00eate, il devra indiquer dans cette rubrique qu\u2019une autre requ\u00eate \u00ab\u00a0suivra\u00a0\u00bb.<\/p>\n<p>Si plusieurs requ\u00eates li\u00e9es concernant une m\u00eame affaire criminelle sont pr\u00e9sent\u00e9es et que le d\u00e9posant n\u2019est pas le m\u00eame, la CCF traitera chaque requ\u00eate s\u00e9par\u00e9ment. Elle tiendra compte uniquement des arguments invoqu\u00e9s par le d\u00e9posant dans le cadre de chaque requ\u00eate.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall su-spoiler-closed\" data-anchor=\"rubrique-12\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h2>12. Rubrique \u00ab Contact \u00bb<\/h2><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Comme indiqu\u00e9 dans la rubrique \u00ab\u00a0Mandataire\u00a0\u00bb, le d\u00e9posant peut utiliser le mod\u00e8le de pouvoir de la CCF pour d\u00e9signer jusqu\u2019\u00e0 trois personnes de contact au sein de l\u2019entit\u00e9 mandataire, laquelle peut \u00eatre un cabinet d\u2019avocats ou une ONG par exemple. La correspondance sera toujours adress\u00e9e \u00e0 l\u2019adresse \u00e9lectronique associ\u00e9e au compte cr\u00e9\u00e9 sur le portail. Toutefois, le d\u00e9posant peut, s\u2019il le souhaite, ajouter dans cette rubrique jusqu\u2019\u00e0 deux autres adresses \u00e9lectroniques qui pourront \u00eatre mises en copie de toute correspondance, pour les personnes de contact indiqu\u00e9es dans le pouvoir.<\/p>\n<p>Le d\u00e9posant doit v\u00e9rifier qu\u2019il n\u2019y a pas de restrictions qui emp\u00eacheraient l\u2019exp\u00e9diteur d\u2019envoyer des messages \u00e0 l\u2019adresse communiqu\u00e9e. Par exemple, les adresses \u00e9lectroniques qui utilisent le syst\u00e8me PEC (Posta Elettronica Certificata) ne sont pas con\u00e7ues pour une utilisation internationale et la CCF ne peut pas envoyer de messages \u00e0 de telles adresses.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall su-spoiler-closed\" data-anchor=\"rubrique-13\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h2>13. Rubrique \u00ab Validation \u00bb<\/h2><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Cette rubrique constitue la derni\u00e8re \u00e9tape de la proc\u00e9dure. En cliquant sur \u00ab\u00a0Envoyer\u00a0\u00bb, le d\u00e9posant transmet la requ\u00eate \u00e0 la CCF et ne peut plus la modifier. La CCF consid\u00e8re que le d\u00e9posant, en traitant la rubrique \u00ab\u00a0Validation\u00a0\u00bb et en transmettant la requ\u00eate, a d\u00fbment sign\u00e9 celle-ci.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall su-spoiler-closed\" data-anchor=\"rubrique-14\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h2>14. Enregistrement d\u2019un brouillon de la requ\u00eate<\/h2><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Le d\u00e9posant souhaitera peut-\u00eatre enregistrer un brouillon de sa requ\u00eate pendant l\u2019\u00e9laboration de celle-ci, soit parce qu\u2019il attend des documents ou des informations compl\u00e9mentaires, soit parce que sa connexion Internet n\u2019est pas fiable et que des sauvegardes r\u00e9guli\u00e8res du formulaire peuvent r\u00e9duire le risque de perdre les informations saisies. Chaque page comporte un bouton \u00ab\u00a0Enregistrer\u00a0\u00bb qui peut \u00eatre utilis\u00e9 \u00e0 cette fin. Une fois le brouillon sauvegard\u00e9, l\u2019utilisateur recevra un lien par courrier \u00e9lectronique \u00e0 l\u2019aide duquel il pourra finaliser la requ\u00eate. Le d\u00e9posant peut aussi acc\u00e9der \u00e0 la requ\u00eate lors de la cr\u00e9ation d\u2019une nouvelle requ\u00eate, en choisissant l\u2019option \u00ab\u00a0Reprendre le brouillon\u00a0\u00bb lorsqu\u2019il est invit\u00e9 \u00e0 le faire.<\/p>\n<p>Lorsque la requ\u00eate est en mode \u00ab\u00a0brouillon\u00a0\u00bb, la CCF ne peut pas voir les documents t\u00e9l\u00e9vers\u00e9s temporairement dans le portail avant la transmission de la requ\u00eate.<\/p>\n<p>Si le d\u00e9posant d\u00e9cide de ne pas transmettre la requ\u00eate initiale (celle dont il avait enregistr\u00e9 un brouillon), il doit cliquer sur \u00ab\u00a0Nouvelle requ\u00eate\u00a0\u00bb dans le menu de d\u00e9part, puis sur \u00ab\u00a0Supprimer et recommencer\u00a0\u00bb.<\/p>\n<p>Il n\u2019est possible d\u2019enregistrer le brouillon que d\u2019une seule requ\u00eate \u00e0 la fois.<\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall su-spoiler-closed\" data-anchor=\"rubrique-15\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h2>15. Une fois que la requ\u00eate a \u00e9t\u00e9 transmise<\/h2><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Une fois la requ\u00eate transmise, un message de confirmation appara\u00eet sur le portail et est \u00e9galement envoy\u00e9 par courrier \u00e9lectronique au d\u00e9posant, avec un lien \u00e0 l\u2019aide duquel ce dernier peut suivre sa requ\u00eate. Le d\u00e9posant peut aussi se connecter \u00e0 tout moment au compte cr\u00e9\u00e9 sur le portail et cliquer sur \u00ab\u00a0Consultation de l\u2019ensemble de vos requ\u00eates\u00a0\u00bb.<\/p>\n<p>Ce message automatique est envoy\u00e9 uniquement \u00e0 l\u2019adresse associ\u00e9e au compte cr\u00e9\u00e9 sur le portail, mais les futurs messages concernant la requ\u00eate seront \u00e9galement envoy\u00e9s en copie aux autres adresses \u00e9ventuellement indiqu\u00e9es dans la rubrique \u00ab\u00a0Contact\u00a0\u00bb.<\/p>\n<p>Le bouton \u00ab\u00a0Imprimer\u00a0\u00bb permet au d\u00e9posant d\u2019imprimer la requ\u00eate ou de l\u2019enregistrer au format PDF.<\/p>\n<p>Les courriers \u00e9lectroniques envoy\u00e9s par la CCF aux d\u00e9posants sont envoy\u00e9s depuis une adresse automatique \u00e0 laquelle il n\u2019est pas possible de r\u00e9pondre. Par cons\u00e9quent, les r\u00e9ponses envoy\u00e9es \u00e0 cette adresse <u><strong>ne seront pas re\u00e7ues<\/strong><\/u> par la CCF. S\u2019il souhaite compl\u00e9ter la requ\u00eate ou y apporter des corrections lors de sa consultation (voir ci-dessus), le d\u00e9posant peut transmettre des informations ou documents compl\u00e9mentaires \u00e0 la CCF en cliquant sur le bouton \u00ab\u00a0Envoyer un message\u00a0\u00bb, en haut \u00e0 droite de l\u2019\u00e9cran. <u>Important<\/u>\u00a0: Les messages envoy\u00e9s ne doivent faire r\u00e9f\u00e9rence qu\u2019\u00e0 la requ\u00eate concern\u00e9e et non \u00e0 plusieurs requ\u00eates.<\/p>\n<p>Si elles peuvent \u00eatre envoy\u00e9es via le bouton \u00ab\u00a0Envoyer un message\u00a0\u00bb, les questions concernant le compte de l\u2019utilisateur, notamment les demandes visant \u00e0 modifier l\u2019adresse \u00e9lectronique associ\u00e9e au compte, peuvent aussi \u00eatre transmises \u00e0 la CCF depuis ce lien\u00a0: <a href=\"https:\/\/ccf-interpol.jotform.com\/app\/ccf-secretariat\/private\/252432948749066\" title=\"https:\/\/ccf-interpol.jotform.com\/app\/ccf-secretariat\/private\/252432948749066\">https:\/\/ccf-interpol.jotform.com\/app\/ccf-secretariat\/private\/252432948749066<\/a>.<\/p>\n<\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Guide d\u2019utilisation du portail de la CCF pour les demandeursPr\u00e9sentation de requ\u00eates \u00e0 la Commission de contr\u00f4le des fichiers d\u2019INTERPOL (CCF) Tout d\u00e9plier Tout replier","protected":false},"author":1,"featured_media":231425,"parent":224859,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-230798","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/europeancourt.org\/fr\/wp-json\/wp\/v2\/pages\/230798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europeancourt.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/europeancourt.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/europeancourt.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/europeancourt.org\/fr\/wp-json\/wp\/v2\/comments?post=230798"}],"version-history":[{"count":31,"href":"https:\/\/europeancourt.org\/fr\/wp-json\/wp\/v2\/pages\/230798\/revisions"}],"predecessor-version":[{"id":231320,"href":"https:\/\/europeancourt.org\/fr\/wp-json\/wp\/v2\/pages\/230798\/revisions\/231320"}],"up":[{"embeddable":true,"href":"https:\/\/europeancourt.org\/fr\/wp-json\/wp\/v2\/pages\/224859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europeancourt.org\/fr\/wp-json\/wp\/v2\/media\/231425"}],"wp:attachment":[{"href":"https:\/\/europeancourt.org\/fr\/wp-json\/wp\/v2\/media?parent=230798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europeancourt.org\/fr\/wp-json\/wp\/v2\/categories?post=230798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europeancourt.org\/fr\/wp-json\/wp\/v2\/tags?post=230798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}