{"id":147731,"date":"2022-07-27T21:57:19","date_gmt":"2022-07-27T19:57:19","guid":{"rendered":"https:\/\/europeancourt.org\/come-compilare\/"},"modified":"2026-07-24T22:58:33","modified_gmt":"2026-07-24T22:58:33","slug":"come-compilare","status":"publish","type":"page","link":"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/formulario-di-ricorso\/come-compilare\/","title":{"rendered":"Come compilare il formulario di ricorso"},"content":{"rendered":"<p class=\"u-text-right\"><em>ITA \u2013 2026\/1<\/em><\/p>\r\n<div class=\"betweendivs\"><a class=\"mybutton blue\" href=\"#\" onclick=\"openall();event.preventDefault();\">Espandi tutto<\/a> <a class=\"mybutton blue\" href=\"#\" onclick=\"closeall();event.preventDefault();\">Comprimi tutto<\/a><\/div>\r\n<div class=\"su-accordion su-u-trim tsfr\">\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall su-spoiler-closed\" data-anchor=\"i\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h2>I. Ci\u00f2 che \u00e8 utile sapere prima di compilare il formulario di ricorso.<br>\r\nLe doglianze che possono essere esaminate dalla Corte<\/h2><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\n<p>La Corte europea dei Diritti dell\u2019Uomo \u00e8 un organo giurisdizionale internazionale competente ad esaminare unicamente ricorsi presentati da persone fisiche, da organizzazioni e da societ\u00e0 che ritengono di aver subito la violazione di diritti riconosciuti dalla <a title=\"Convenzione per la salvaguardia dei Diritti dell\u2019Uomo e delle Libert\u00e0 fondamentali\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/convenzione-europea-dei-diritti-delluomo\/\">Convenzione europea dei diritti dell\u2019uomo<\/a>. Detta Convenzione \u00e8 un trattato internazionale mediante il quale un gran numero di Stati europei si sono impegnati a proteggere alcuni diritti fondamentali. Tali diritti sono enunciati nella Convenzione e nei suoi Protocolli no <a title=\"Protocollo addizionale alla Convenzione per la salvaguardia dei Diritti dell\u2019Uomo e delle Libert\u00e0 fondamentali\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/convenzione-europea-dei-diritti-delluomo\/protocollo-n1\/\">1<\/a>, <a title=\"Protocollo n. 4 alla Convenzione per la salvaguardia dei Diritti dell\u2019Uomo e delle Libert\u00e0 fondamentali\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/convenzione-europea-dei-diritti-delluomo\/protocollo-n4\/\">4<\/a>, <a title=\"Protocollo n. 6 alla Convenzione per la salvaguardia dei Diritti dell\u2019Uomo e delle Libert\u00e0 fondamentali\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/convenzione-europea-dei-diritti-delluomo\/protocollo-n6\/\">6<\/a>, <a title=\"Protocollo n. 7 alla Convenzione per la salvaguardia dei Diritti dell\u2019Uomo e delle Libert\u00e0 fondamentali\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/convenzione-europea-dei-diritti-delluomo\/protocollo-n7\/\">7<\/a>, <a title=\"Protocollo n. 12 alla Convenzione per la salvaguardia dei Diritti dell\u2019Uomo e delle Libert\u00e0 fondamentali\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/convenzione-europea-dei-diritti-delluomo\/protocollo-n12\/\">12<\/a> e <a title=\"Protocollo n. 13 alla Convenzione per la salvaguardia dei Diritti dell\u2019Uomo e delle Libert\u00e0 fondamentali\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/convenzione-europea-dei-diritti-delluomo\/protocollo-n13\/\">13<\/a>. Questi protocolli non sono stati ratificati da tutti gli Stati. La invitiamo pertanto a prendere visione dei relativi testi, che trover\u00e0 in allegato.<\/p>\r\n<p>La Corte non pu\u00f2 esaminare qualsiasi tipo di doglianza. La sua competenza \u00e8 delimitata dai criteri di ricevibilit\u00e0 enunciati nella Convenzione, che stabiliscono chi pu\u00f2 adire la Corte, quando e in quali casi. Oltre il 90% dei ricorsi esaminati dalla Corte vengono dichiarati irricevibili. \u00c8 quindi importante verificare che le doglianze sollevate rispondano ai criteri di ricevibilit\u00e0 esposti qui di seguito.<\/p>\r\n<p>La Corte pu\u00f2 esaminare unicamente ricorsi che soddisfino i seguenti requisiti:<\/p>\r\n<ul class=\"ec-guidance-list\">\r\n\t<li>le doglianze devono riguardare la violazione di uno o pi\u00f9 <strong>diritti garantiti dalla Convenzione e dai suoi Protocolli<\/strong>;<\/li>\r\n\t<li>le doglianze devono essere dirette <strong>contro uno Stato che ha ratificato<\/strong> la Convenzione e, se del caso, il Protocollo che garantisce il diritto relativo alla violazione lamentata (<em>non tutti gli Stati hanno ratificato tutti i Protocolli; verificare la <a title=\"Convenzione per la salvaguardia dei Diritti dell\u2019Uomo e delle Libert\u00e0 fondamentali e suoi Protocolli\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/\">lista delle ratifiche<\/a> disponibile sul sito internet della Corte: www.echr.coe.int\/applicants<\/em>);<\/li>\r\n\t<li>le doglianze devono riguardare questioni che implichino la responsabilit\u00e0 di un\u2019autorit\u00e0 pubblica (legislatore, organo amministrativo, organo giudiziario, ecc.) \u2013 la Corte non pu\u00f2 trattare ricorsi diretti contro privati o contro organismi privati;<\/li>\r\n\t<li>le doglianze devono riguardare <strong>atti o fatti intervenuti dopo la data di ratifica<\/strong> della Convenzione o del relativo Protocollo da parte dello Stato convenuto (per ogni Stato, vedere le <a title=\"Convenzione per la salvaguardia dei Diritti dell\u2019Uomo e delle Libert\u00e0 fondamentali e suoi Protocolli\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/\">date indicate nella lista delle ratifiche<\/a> disponibile sul sito internet della Corte: www.echr.coe.int\/applicants);<\/li>\r\n\t<li>il ricorrente deve aver subito, <strong>personalmente e direttamente<\/strong>, gli effetti della violazione di un diritto fondamentale (deve possedere lo \u00abstatus di vittima\u00bb);<\/li>\r\n\t<li>il ricorrente deve aver previamente consentito all\u2019ordinamento giuridico interno di porre rimedio alla violazione dei suoi diritti (\u00abesaurimento delle vie di ricorso interne\u00bb). Ci\u00f2 significa in generale che, prima di adire la Corte, <strong>il ricorrente deve aver presentato le stesse doglianze dinanzi agli organi giurisdizionali nazionali<\/strong>, ivi compresa la pi\u00f9 alta giurisdizione, rispettando le regole nazionali di procedura, in particolare i termini di decadenza. Di contro, non \u00e8 obbligatorio esperire ricorsi privi di efficacia o le vie di ricorso discrezionali o straordinarie non facenti parte delle normali procedure di ricorso;  <\/li>\r\n\t<li>il ricorso deve essere presentato alla Corte, completo in ogni sua parte, <strong>entro un termine di quattro mesi dalla decisione interna definitiva<\/strong>. Il termine di quattro mesi inizia solitamente a decorrere dalla data alla quale la pi\u00f9 alta istanza nazionale competente ha reso la sua decisione oppure dalla data alla quale tale decisione \u00e8 stata resa nota al ricorrente o al suo rappresentante. Laddove, per una particolare doglianza, non esista un ricorso effettivo, il termine di quattro mesi inizia a decorrere dalla data dell\u2019atto, del fatto o della decisione oggetto della doglianza.  Il termine di quattro mesi \u00e8 interrotto unicamente dall\u2019invio alla Corte di un ricorso completo che rispetti i requisiti di cui all\u2019<a title=\"Articolo 47 del Regolamento della Corte Europea dei Diritti dell\u2019Uomo\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/regolamento-articolo-47\/\">articolo 47 del Regolamento della Corte<\/a> (vedere il testo pubblicato nel <a title=\"Kit per i ricorrenti alla Corte Europea dei Diritti dell\u2019Uomo\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/\">kit per i ricorrenti<\/a>). Detto termine scade l\u2019ultimo giorno dei quattro mesi, anche se trattasi di domenica o di giorno festivo. <u>Il formulario di ricorso, nonch\u00e9 tutte le informazioni e i documenti richiesti, devono pertanto essere inviati alla Corte al pi\u00f9 tardi entro l\u2019ultimo giorno del termine di quattro mesi<\/u>: \u00e8 quindi essenziale spedirli via posta in tempo utile;  <\/li>\r\n\t<li>le doglianze del ricorrente <strong>devono fondarsi su solide basi<\/strong> desumibili da un\u2019esposizione chiara dei fatti accaduti, corredata da documenti, decisioni, referti medici, testimonianze e altri documenti giustificativi;<\/li>\r\n\t<li>Il ricorrente deve essere in grado di dimostrare che i fatti di cui si lamenta hanno causato un danno ingiustificabile ad un diritto fondamentale. Non \u00e8 possibile semplicemente lamentarsi di un provvedimento giudiziario ritenuto ingiusto o errato. La Corte non \u00e8 un giudice d\u2019appello delle decisioni emesse dagli organi giurisdizionali nazionali e non pu\u00f2 quindi annularle n\u00e9 modificarle; <\/li>\r\n\t<li>Le doglianze sottoposte non devono essere gi\u00e0 state esaminate dalla Corte n\u00e9 da un altro organo giurisdizionale internazionale.<\/li>\r\n<\/ul>\r\n<p>\u00c8 altres\u00ec utile tener presente che la Corte riceve ogni anno diverse decine di migliaia di ricorsi e che non dispone di risorse sufficienti per esaminare ricorsi futili, gi\u00e0 sottoposti, o privi di sostanza: non rientra nelle competenze di un organo giurisdizionale internazionale l\u2019esame di questo tipo di casi, che potrebbero essere rigettati per abuso del diritto di ricorso, alla stessa stregua di quanto accade in caso di ricorsi contenenti espressioni offensive o insulti.<\/p>\r\n<p>Un ricorso pu\u00f2 anche essere rigettato in presenza dei due elementi seguenti: i fatti di cui si lamenta il ricorrente non gli causino danni reali e significativi e non sollevino nessuna nuova questione relativa ai diritti dell\u2019uomo che necessiti un esame sul piano internazionale.<\/p>\r\n<p>Al fine di ottenere maggiori informazioni su tali criteri, \u00e8 possibile <a href=\"https:\/\/europeancourt.org\/en\/legal-advice-and-contacts\/\" title=\"Rivolgersi ad un avvocato \u2013 Corte europea dei diritti dell\u2019uomo\">rivolgersi ad un avvocato<\/a> oppure consultare il sito internet della Corte che fornisce informazioni sui criteri di ricevibilit\u00e0 e risposte alle domande pi\u00f9 frequenti.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall su-spoiler-closed\" data-anchor=\"ii\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h2>II. Come compilare il formulario di ricorso <\/h2><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>Le condizioni da rispettare al fine di compilare in maniera corretta il formulario di ricorso sono indicate nell\u2019<a title=\"Articolo 47 del Regolamento della Corte Europea dei Diritti dell\u2019Uomo\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/regolamento-articolo-47\/\">articolo 47 del regolamento della Corte<\/a> (disponibile nel <a title=\"Kit per i ricorrenti alla Corte Europea dei Diritti dell\u2019Uomo\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/\">kit del ricorrente<\/a>). Ulteriori informazioni sono contenute nelle <a title=\"Introduzione dell\u2019istanza \u2013 Istruzione pratica\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/istruzione-per-lintroduzione-dellistanza\/\">Istruzioni pratiche relative all\u2019introduzione del ricorso<\/a>, in allegato al regolamento e disponibili nel sito internet della Corte (www.echr.int\/applicants). Infine, qui di seguito sono indicati dei consigli e delle spiegazioni pratiche. Se ne consiglia la lettura prima di compilare il formulario al fine di evitare di commettere degli errori che rischierebbero di rendere il ricorso incompleto, destinato ad essere rigettato.<\/p>\r\n<ul class=\"ec-guidance-list\">\r\n\t<li>SCRIVERE IN MANIERA LEGGIBILE. \u00c8 preferibile dattilografare le risposte. <\/li>\r\n\t<li>COMPILARE TUTTE LE SEZIONI CORRISPONDENTI AL CASO DI SPECIE. In caso contrario, il formulario di ricorso risulter\u00e0 incompleto e non verr\u00e0 portato all\u2019esame della Corte. <\/li>\r\n\t<li>Non utilizzare n\u00e9 simboli n\u00e9 abbreviazioni: esprimersi in termini chiari utilizzando parole complete.<\/li>\r\n\t<li>UTILIZZARE UN LINGUAGGIO CONCISO.<\/li>\r\n<\/ul>\r\n<p class=\"ec-doc-callout\"><strong>Scaricare il <a href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/formulario-di-ricorso\/\" title=\"Formulario di ricorso alla Corte europea dei diritti dell\u2019uomo\"><strong>formulario di ricorso<\/strong><\/a> dal sito internet della Corte e, se possibile, compilarlo on-line.<\/strong> Tale procedura render\u00e0 pi\u00f9 rapida la trattazione del ricorso.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-1 su-spoiler-closed\" data-anchor=\"lingua\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>Lingua<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>Le <strong>lingue ufficiali<\/strong> della Corte sono il francese e l\u2019inglese, ma se si preferisce ci si pu\u00f2 rivolgere alla Cancelleria utilizzando la lingua ufficiale di uno degli Stati che hanno ratificato la Convenzione. Durante la sola fase iniziale della procedura, anche la Corte potrebbe inviare lettere in questa lingua. Tuttavia, nel prosieguo della procedura, cio\u00e8 nel caso in cui la Corte decida di invitare il governo convenuto a presentare osservazioni scritte sulle doglianze sollevate, tutta la corrispondenza successiva sar\u00e0 redatta in francese o in inglese. In tal caso, il ricorrente, o il suo rappresentante, dovr\u00e0 utilizzare il francese o l\u2019inglese nelle ulteriori osservazioni.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-1 su-spoiler-closed\" data-anchor=\"campi\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>Note relative ai campi del formulario di ricorso<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>Affinch\u00e9 un formulario di ricorso venga accettato dalla Corte, \u00e8 necessario che tutti i campi applicabili al caso del ricorrente siano riempiti nel modo indicato, allegando tutti i documenti richiesti dall\u2019<a title=\"Articolo 47 del Regolamento della Corte Europea dei Diritti dell\u2019Uomo\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/regolamento-articolo-47\/\">articolo 47 del regolamento<\/a>. Si raccomanda di provvedere a quanto sopraindicato al momento della compilazione del formulario e della produzione dei documenti a supporto delle doglianze esposte. <strong>In caso contrario, la Corte non esaminer\u00e0 il ricorso: non verr\u00e0 aperto alcun fascicolo e non verr\u00e0 conservato alcun documento. <\/strong><\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-1 su-spoiler-closed\" data-anchor=\"utilizzo-di-strumenti-dell-intelligenza-artificiale-in-fase-di-compilazione-del-formulario\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>Utilizzo di strumenti dell\u2019intelligenza artificiale in fase di compilazione del formulario &#091;di ricorso&#093;<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\n<p>Qualora il ricorrente utilizzi strumenti di intelligenza artificiale (IA) per la compilazione del [formulario] di ricorso, rimane pienamente responsabile del contenuto presentato alla Corte. Si raccomanda pertanto di verificare che tutte le informazioni fattuali, le argomentazioni giuridiche e i riferimenti alla giurisprudenza o ad altre fonti generati o suggeriti da tali strumenti siano accurati, pertinenti e completi.<\/p>\r\n<p>Si prega di notare che la presentazione consapevole di fatti non veritieri, dichiarazioni false o informazioni incomplete e quindi fuorvianti pu\u00f2 comportare l\u2019irricevibilit\u00e0 del [ricorso], per abuso del diritto di ricorso ai sensi <a href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/convenzione-europea-dei-diritti-delluomo\/#articolo-35\" title=\"Articolo 35 della Convenzione per la salvaguardia dei Diritti dell\u2019Uomo e delle Libert\u00e0 fondamentali\">[dell\u2019articolo 35 \u00a7 3 della Convenzione]<\/a>.<\/p>\r\n<\/div><\/div>\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-1 su-spoiler-closed\" data-anchor=\"sezione-per-sezione\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>Il formulario di ricorso \u2013 sezione per sezione<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>I termini utilizzati nel <a href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/formulario-di-ricorso\/\" title=\"Formulario di ricorso alla Corte europea dei diritti dell\u2019uomo\">formulario di ricorso<\/a> e nelle presenti avvertenze sono ripresi dalla <a title=\"Convenzione per la salvaguardia dei Diritti dell\u2019Uomo e delle Libert\u00e0 fondamentali\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/convenzione-europea-dei-diritti-delluomo\/\">Convenzione<\/a> e il mancato utilizzo del genere femminile a fianco del genere maschile non comporta alcun tipo di esclusione.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-2 su-spoiler-closed\" data-anchor=\"codice-a-barre\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h4>Riquadro riservato al codice a barre<\/h4><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>Se \u00e8 gi\u00e0 in corso uno scambio di corrispondenza con la Corte avente lo stesso oggetto e il ricorrente ha gi\u00e0 ricevuto le etichette a codice a barre, occorrer\u00e0 incollarne una nello spazio apposito situato nella parte superiore sinistra della prima pagina del <a href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/formulario-di-ricorso\/\" title=\"Formulario di ricorso alla Corte europea dei diritti dell\u2019uomo\">formulario<\/a>.<\/p><\/div><\/div>\r\r\n<h4 class=\"su-spoiler-title ec-fake-spoiler-heading padding-left-level-2\" id=\"%D1%80%D0%B0%D0%B7%D0%B4%D0%B5%D0%BB-a\">A. Ricorrente<\/h4>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-3 su-spoiler-closed\" data-anchor=\"sezione-a-1\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h5>A.1. Privato <\/h5><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>Questa sezione riguarda i ricorrenti persone fisiche e non i ricorrenti persone giuridiche, come ad esempio societ\u00e0 o associazioni (sezione A.2).<\/p>\r\n<p><strong>1\u20139.<\/strong> Nel caso vi sia pi\u00f9 di un ricorrente, \u00e8 necessario fornire informazioni specifiche per ogni ricorrente successivo al primo, utilizzando un foglio separato e indicando i ricorrenti in ordine numerico. Vedere anche la rubrica \u00abRicorsi di gruppo e molteplicit\u00e0 di ricorrenti\u00bb qui di seguito.<\/p>\r\n<p><strong>6.<\/strong> Indirizzo: il ricorrente deve fornire un indirizzo postale diverso da quello dell\u2019avvocato o del rappresentante affinch\u00e9 la Corte possa contattarlo se necessario. Nel caso in cui il ricorrente non disponga di un domicilio fisso potr\u00e0 fornire l\u2019indirizzo di una casella postale o quella di un amico e dovr\u00e0, in questo caso, fornire una spiegazione di tale scelta.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-3 su-spoiler-closed\" data-anchor=\"sezione-a-2\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h5>A.2. Organizzazione <\/h5><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>Questa sezione riguarda i ricorrenti persone giuridiche (societ\u00e0, organizzazioni non governative, associazioni, ecc.): nel caso in cui venga compilata, compilare anche la sezione D.1.<\/p>\r\n<p><strong>10\u201316.<\/strong> \u00c8 necessario indicare i dati identificativi e di contatto dell\u2019organizzazione ricorrente. Nel caso ve ne sia pi\u00f9 di una, \u00e8 necessario fornire informazioni specifiche per ogni singola organizzazione utilizzando un foglio separato e indicando i ricorrenti in ordine numerico progressivo.<\/p>\r\n<p><strong>11.<\/strong> Numero di registrazione: indicare in questa rubrica il numero d\u2019immatricolazione, d\u2019identificazione o d\u2019iscrizione nel registro ufficiale, a seconda dei casi.<\/p>\r\n<p><strong>12.<\/strong> \u00c8 altres\u00ec necessario indicare, se del caso, la data di registrazione, di costituzione o d\u2019incorporazione dell\u2019organizzazione, al fine di facilitarne l\u2019identificazione.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-3 su-spoiler-closed\" data-anchor=\"ricorsi-raggruppati\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h5>Ricorsi raggruppati e ricorrenti multipli<\/h5><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>Se un ricorrente o un rappresentante introduce, per conto di pi\u00f9 ricorrenti, ricorsi basati su fatti diversi, \u00e8 necessario utilizzare un formulario di ricorso per ogni singolo ricorrente, indicando tutte le informazioni richieste e allegando i documenti relativi ad ogni ricorrente al formulario corrispondente.<\/p>\r\n<p>Nel caso vi siano pi\u00f9 di dieci ricorrenti, il rappresentante deve produrre, oltre ai formulari di ricorso e ai documenti, una tabella riepilogativa nella quale figurino i nomi e i dati di ogni ricorrente. Tale <a href=\"https:\/\/europeancourt.org\/downloads\/it\/Tabella_che_riassuma_le_informazioni_personali_richieste_per_ciascun_ricorrente_alla_CEDU_ITA.XLSX\" title=\"Tabella che riassuma le informazioni personali richieste per ciascun ricorrente alla Corte europea dei diritti dell\u2019uomo\">tabella<\/a> pu\u00f2 essere scaricata dal sito internet della Corte (www.echr.coe.int\/applicants). Nel caso in cui il rappresentante sia un avvocato, questa tabella dovr\u00e0 anche essere fornita in formato elettronico (CD-ROM o chiave USB).<\/p>\r\n<p>Quando un caso riguarda un elevato numero di ricorrenti o di ricorsi, la Cancelleria pu\u00f2 chiedere ai ricorrenti o ai loro rappresentanti di fornire il testo delle loro osservazioni e dichiarazioni o dei loro documenti per via elettronica o secondo modalit\u00e0 diverse. La Cancelleria pu\u00f2 altres\u00ec formulare ulteriori richieste volte a facilitare il trattamento rapido ed efficace dei ricorsi.<\/p>\r\n<p>Il mancato rispetto delle istruzioni della Cancelleria su forma e presentazione dei ricorsi di gruppo o presentati da pi\u00f9 ricorrenti potrebbe avere come conseguenza il non esame dei ricorsi da parte della Corte (<a title=\"Articolo 47 del Regolamento della Corte Europea dei Diritti dell\u2019Uomo\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/regolamento-articolo-47\/\">articolo 47 \u00a7\u00a7 5.1 e 5.2 del regolamento<\/a>).<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-2 su-spoiler-closed\" data-anchor=\"sezione-b\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h4>B. Stato\/i contro il\/i quale\/i il ricorso \u00e8 introdotto<\/h4><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p><strong>17.<\/strong> Selezionare la o le caselle corrispondente\/i allo Stato\/agli Stati contro il\/i quale\/i il ricorso \u00e8 introdotto.<\/p>\r\n<p>Si tratta dello Stato o degli Stati che il ricorrente ritiene responsabile(i) dei fatti di cui si lamenta. Tenere presente che le doglianze presentate dinanzi la Corte possono essere introdotte unicamente contro gli Stati che figurano in questa lista: si tratta degli Stati che fanno parte del sistema della Convenzione.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-2 su-spoiler-closed\" data-anchor=\"sezione-c\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h4>C. Rappresentante\/i di un privato<\/h4><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>La persona designata come rappresentante in questa sezione deve apporre la propria firma all\u2019interno del riquadro 35; il ricorrente deve a sua volta apporre la propria firma all\u2019interno del riquadro 33.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-3 su-spoiler-closed\" data-anchor=\"sezione-c-1\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h5>C.1. Rappresentante diverso da un avvocato <\/h5><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p><strong>18\u201325.<\/strong> Alcuni ricorrenti possono decidere di non prendere parte alla procedura o possono non essere in grado di farlo, ad esempio per motivi di salute o di incapacit\u00e0. In questi casi, possono farsi rappresentare da un\u2019altra persona, anche senza formazione giuridica. Ad esempio, un genitore pu\u00f2 rappresentare un proprio figlio; un tutore, un membro della famiglia o un partner pu\u00f2 rappresentare una persona che, per motivi pratici o medici, ha difficolt\u00e0 a prendere parte alla procedura (ad esempio, un ricorrente ricoverato o detenuto). In questi casi, sar\u00e0 necessario indicare a che titolo la persona designata rappresenter\u00e0 il ricorrente o le relazioni che legano ricorrente e rappresentante, nonch\u00e9 l\u2019identit\u00e0 di quest\u2019ultimo e i suoi dati. Nel caso in cui si sia compilata la sezione C.1 e si intenda altres\u00ec nominare un avvocato, \u00e8 necessario compilare anche la sezione C.2 (di cui qui sotto).<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-3 su-spoiler-closed\" data-anchor=\"sezione-c-2\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h5>C.2. Avvocato <\/h5><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p><strong>26\u201332.<\/strong> \u00c8 necessario indicare nome, cognome e dati completi dell\u2019avvocato che rappresenta il ricorrente dinanzi alla Corte. Al momento dell\u2019introduzione del ricorso, <u>non<\/u> \u00e8 obbligatorio avvalersi di un avvocato. Il ricorrente verr\u00e0 informato della fase in cui la procedura raggiunger\u00e0 una fase in cui l\u2019assistenza di un avvocato diventer\u00e0 necessaria. A questo stadio, dopo che la Corte avr\u00e0 deciso di comunicare il ricorso al governo convenuto per sollecitare le sue osservazioni scritte, il ricorrente potr\u00e0 ottenere un contributo per le spese legali nel caso in cui non disponga di mezzi sufficienti per farvi fronte e qualora la concessione di tale assistenza sia ritenuta necessaria per il corretto svolgimento della procedura. In tal caso, il ricorrente ne verr\u00e0 informato in tempo utile.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-3 su-spoiler-closed\" data-anchor=\"sezione-c-3\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h5>C.3. Procura <\/h5><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>Questa sezione deve contenere delle firme originali.<\/p>\r\n<p><strong>33.<\/strong> Nel caso in cui il ricorrente sia un privato, dovr\u00e0 firmare una procura che autorizzi il rappresentante ad agire in suo nome e conto, tranne il caso in cui egli sia impossibilitato a firmare perch\u00e9, ad esempio, minorenne, interdetto o incapace. Il rappresentante che non sia un avvocato, che dia incarico ad un avvocato ad agire in nome e per conto del ricorrente impossibilitato a firmare, deve firmare la procura a nome del ricorrente.<\/p>\r\n<p><strong>34 e 36.<\/strong> La data da indicare in queste sezioni \u00e8 quella alla quale il ricorrente e il suo rappresentante firmeranno la procura.<\/p>\r\n<p><strong>35.<\/strong> La persona incaricata dal ricorrente di introdurre il ricorso dinanzi la Corte, che si tratti di un avvocato o meno, deve indicare di accettare il mandato conferitole. In mancanza di tale firma, la Cancelleria continuer\u00e0 a corrispondere unicamente con il ricorrente poich\u00e9 non \u00e8 stata fornita prova dell\u2019effettiva volont\u00e0 del rappresentante di accettare detto incarico.<\/p>\r\n<p>Si prega di <u>non<\/u> inviare una procura separata: la Corte deve disporre, all\u2019interno del <a href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/formulario-di-ricorso\/\" title=\"Formulario di ricorso alla Corte europea dei diritti dell\u2019uomo\">formulario di ricorso<\/a>, di tutte le informazioni pertinenti relative all\u2019identit\u00e0 e ai dati delle persone oggetto del ricorso. Il ricorrente e il suo rappresentante devono apporre la propria firma all\u2019interno dei riquadri 33 e 35 della sezione \u00abProcura\u00bb del formulario al momento della preparazione del ricorso: tranne nel caso di ostacoli pratici insormontabili, gli avvocati non devono presentare il formulario di ricorso corredato da una procura in un documento separato. Soltanto nel caso in cui un ricorrente dovesse cambiare avvocato dopo aver introdotto il ricorso, la Corte accetter\u00e0 una procura separata.   In tal caso, sar\u00e0 necessario utilizzare il <a title=\"Formulario di procura per la Corte europea dei diritti dell\u2019uomo\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/formulario-di-procura\/\">formulario previsto a tal fin<\/a> e disponibile nel sito internet della Corte. Tale documento contiene tutte le informazioni richieste. Nel caso in cui dovesse essere inviata alla Corte una procura separata senza una spiegazione convincente che dimostri l\u2019impossibilit\u00e0 di fare altrimenti, il ricorso verr\u00e0 rigettato per mancato rispetto dell\u2019<a title=\"Articolo 47 del Regolamento della Corte Europea dei Diritti dell\u2019Uomo\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/regolamento-articolo-47\/\">articolo 47 del regolamento<\/a>.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-3 su-spoiler-closed\" data-anchor=\"sezione-c-ecomms\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h5>Comunicazione elettronica tra il rappresentante e la Corte<\/h5><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>\u00abeComms\u00bb \u00e8 un servizio attivato dalla Corte per permettere le comunicazioni elettroniche (per via telematica) con il rappresentante di un ricorrente. <strong>Il servizio \u00e8 attivato solo nel momento in cui il ricorso \u00e8 comunicato al Governo, ed esclusivamente in questo caso.<\/strong><\/p>\r\n<p><strong>37.<\/strong> L\u2019indirizzo elettronico fornito sar\u00e0 utilizzato per creare un account eComms. Si invitano i rappresentanti che esercitano all\u2019interno di uno Studio legale a fornire un indirizzo elettronico generico affinch\u00e9 l\u2019account possa essere accessibile da pi\u00f9 utenti all\u2019interno dello Studio.<\/p>\r\n<p>E\u2019 necessario informare la Corte di ogni cambiamento riguardante l\u2019indirizzo elettronico associato al vostro account eComms.<\/p>\r\n<p>Per maggiori informazioni, \u00e8 possible consultare le condizioni generali d\u2019utilizzo sulla pagina web dedicata a eComms (https:\/\/ecomms.echr.coe.int), cos[\u00ec] come l\u2019istruzione pratica sull\u2019invio elettronico dei documenti da parte dei ricorrenti (www.echr.coe.int\/practicedirections) (disponibili unicamente in inglese e francese).<\/p><\/div><\/div>\r\r\n<h4 class=\"su-spoiler-title ec-fake-spoiler-heading padding-left-level-2\" id=\"%D1%80%D0%B0%D0%B7%D0%B4%D0%B5%D0%BB-d\">D. Rappresentante\/i di un\u2019organizzazione<\/h4>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-3 su-spoiler-closed\" data-anchor=\"sezione-d-1\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h5>D.1. Rappresentante dell\u2019organizzazione <\/h5><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p><strong>38\u201345.<\/strong> Nel caso in cui il ricorrente sia un\u2019organizzazione, quest\u2019ultima deve stare in giudizio tramite una persona autorizzata ad agire a suo nome e con la quale la Corte possa corrispondere se necessario, ad esempio uno dei suoi responsabili ufficiali, il suo presidente o uno dei suoi direttori. La persona designata a tal fine deve fornire delle prove documentali relative al suo diritto di adire le autorit\u00e0 giudiziarie a nome dell\u2019organizzazione: ad esempio, a seconda della pratica vigente nel paese interessato, una copia dell\u2019estratto del registro delle societ\u00e0 o della camera di commercio, un\u2019autorizzazione notarile o un verbale dell\u2019istanza dirigente. Nel caso in cui non fosse possibile presentare nessuna di queste prove documentali, sar\u00e0 necessario fornire una spiegazione.<\/p>\r\n<p>In questa sezione \u00e8 necessario indicare il nome completo e i dati della persona legalmente o giuridicamente abilitata ad agire per conto dell\u2019organizzazione.<\/p>\r\n<p>Nel caso in cui il rappresentante ufficiale dell\u2019organizzazione sia anche l\u2019avvocato che agisce per conto di questa organizzazione, \u00e8 necessario indicarlo chiaramente compilando al contempo sia questa sezione che la sezione D.2.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-3 su-spoiler-closed\" data-anchor=\"sezione-d-2\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h5>D.2. Avvocato <\/h5><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p><strong>46\u201352.<\/strong> \u00c8 necessario indicare il nome e i dati completi dell\u2019avvocato che rappresenta l\u2019organizzazione dinanzi la Corte. Allo stadio dell\u2019introduzione del ricorso, <u>non<\/u> \u00e8 obbligatorio avvalersi di un avvocato. Il ricorrente verr\u00e0 informato nel momento in cui la procedura raggiunger\u00e0 una fase in cui l\u2019assistenza di un avvocato diventer\u00e0 necessaria.<\/p>\r\n<p>La persona designata come avvocato in questa sezione dovr\u00e0 apporre la propria firma all\u2019interno del riquadro 55; il rappresentante dell\u2019organizzazione dovr\u00e0 apporre la propria firma nel riquadro 53.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-3 su-spoiler-closed\" data-anchor=\"sezione-d-3\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h5>D.3. Procura <\/h5><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>Questa sezione deve contenere delle firme originali.<\/p>\r\n<p><strong>53.<\/strong> Il rappresentante dell\u2019organizzazione ricorrente dovr\u00e0 firmare la procura al fine di autorizzare l\u2019avvocato ad agire per conto dell\u2019organizzazione.<\/p>\r\n<p><strong>54 e 56.<\/strong> La data da indicare in queste sezioni \u00e8 quella alla quale il rappresentante dell\u2019organizzazione e l\u2019avvocato incaricato firmeranno la procura.<\/p>\r\n<p><strong>55.<\/strong> L\u2019avvocato incaricato dal rappresentante dell\u2019organizzazione alla presentazione del ricorso dinanzi la Corte deve firmare la procura per indicare che accetta il mandato conferitogli. In mancanza di tale firma, la Cancelleria continuer\u00e0 a corrispondere unicamente con il rappresentante dell\u2019organizzazione poich\u00e9 non sar\u00e0 stata fornita prova dell\u2019effettiva volont\u00e0 dell\u2019avvocato di accettare detto incarico.<\/p>\r\n<p>Si prega di <u>non<\/u> inviare una procura separata: la Corte deve disporre, all\u2019interno del <a href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/formulario-di-ricorso\/\" title=\"Formulario di ricorso alla Corte europea dei diritti dell\u2019uomo\">formulario di ricorso<\/a>, di tutte le informazioni pertinenti relative all\u2019identit\u00e0 e ai dati delle persone oggetto del ricorso. Il rappresentante dell\u2019organizzazione e l\u2019avvocato devono apporre la propria firma all\u2019interno dei riquadri 53 e 55 della sezione \u00abProcura\u00bb del formulario al momento della preparazione del ricorso: tranne nel caso di ostacoli pratici insormontabili, gli avvocati non devono presentare il formulario di ricorso correlato da una procura in un documento separato. Soltanto nel caso in cui un ricorrente dovesse cambiare avvocato dopo aver introdotto il ricorso, la Corte accetter\u00e0 una procura separata.   In tal caso, sar\u00e0 necessario utilizzare il <a title=\"Formulario di procura per la Corte europea dei diritti dell\u2019uomo\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/formulario-di-procura\/\">formulario previsto a tal fin<\/a> e disponibile nel sito internet della Corte. Tale documento contiene tutte le informazioni richieste. Nel caso in cui dovesse essere inviata alla Corte una procura separata senza una spiegazione convincente che dimostri l\u2019impossibilit\u00e0 di fare altrimenti, il ricorso verr\u00e0 rigettato per mancato rispetto dell\u2019<a title=\"Articolo 47 del Regolamento della Corte Europea dei Diritti dell\u2019Uomo\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/regolamento-articolo-47\/\">articolo 47 del regolamento<\/a>.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-3 su-spoiler-closed\" data-anchor=\"sezione-d-ecomms\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h5>Comunicazione elettronica tra il rappresentante e la Corte<\/h5><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>\u00abeComms\u00bb \u00e8 un servizio attivato dalla Corte per permettere le comunicazioni elettroniche (per via telematica) con il rappresentante di un\u2019organizzazione ricorrente. <strong>Il servizio \u00e8 attivato solo nel momento in cui il ricorso \u00e8 comunicato al Governo, ed esclusivamente in questo caso.<\/strong><\/p>\r\n<p><strong>57.<\/strong> L\u2019indirizzo elettronico fornito sar\u00e0 utilizzato per creare un account eComms. Si invitano i rappresentanti che esercitano all\u2019interno di uno Studio legale a fornire un indirizzo elettronico generico affinch\u00e9 l\u2019account possa essere accessibile da pi\u00f9 utenti all\u2019interno dello Studio.<\/p>\r\n<p>E\u2019 necessario informare la Corte di ogni cambiamento riguardante l\u2019indirizzo elettronico associato al vostro account eComms.<\/p>\r\n<p>Per maggiori informazioni, \u00e8 possible consultare le condizioni generali d\u2019utilizzo sulla pagina web dedicata a eComms (https:\/\/ecomms.echr.coe.int), cos[\u00ec] come l\u2019istruzione pratica sull\u2019invio elettronico dei documenti da parte dei ricorrenti (www.echr.coe.int\/practicedirections) (disponibili unicamente in inglese e francese).<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-2 su-spoiler-closed\" data-anchor=\"oggetto-del-ricorso\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h4>E, F e G: Oggetto del ricorso<\/h4><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p><strong>58\u201365.<\/strong> Utilizzare uno stile conciso. Fornire le informazioni essenziali relative al caso oggetto di ricorso, indicando fatti e decisioni pertinenti nonch\u00e9 la maniera in cui i Suoi diritti sono stati violati. Non menzionare n\u00e9 circostanze irrilevanti n\u00e9 questioni secondarie. Non inserire lunghe citazioni. \u00c8 sempre possibile rinviare a documenti allegati.    I fatti e le doglianze devono essere inseriti nello spazio previsto all\u2019interno del <a href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/formulario-di-ricorso\/\" title=\"Formulario di ricorso alla Corte europea dei diritti dell\u2019uomo\">formulario di ricorso<\/a>, affinch\u00e9 la Corte possa stabilire natura e oggetto del ricorso senza doversi riferire ad altri documenti. Tali informazioni sono fondamentali per un\u2019analisi efficace e rapida dello stesso. Esse devono figurare nelle pagine corrispondenti del formulario di ricorso e non su documenti allegati. \u00c8 pertanto necessario esporre i fatti, le doglianze e le informazioni relative al rispetto dei criteri di ricevibilit\u00e0 in maniera chiara, concisa e leggibile. Non tentare, ad esempio, di far rientrare un\u2019esposizione dei fatti troppo dettagliata all\u2019interno dello spazio disponibile scrivendo con caratteri pi\u00f9 piccoli o troppo ravvicinati. Evitare altres\u00cc di scrivere semplicemente formule del tipo \u00abvedasi documento allegato\u00bb. \u00c8 necessario indicare le informazioni pertinenti limitandosi ad utilizzare lo spazio previsto a tal fine all\u2019interno del formulario. In caso contrario, la Corte non esaminer\u00e0 il ricorso.<\/p>\r\n<p>Se necessario, \u00e8 possibile allegare al formulario di ricorso, in un documento separato, informazioni o spiegazioni supplementari, purch\u00e9 non superino un totale di 20 pagine (escluse le decisioni e i documenti allegati). Ci\u00f2 non significa che sia possibile iniziare l\u2019esposizione dei fatti nel formulario di ricorso e terminarla sui fogli supplementari fino a raggiungere le 20 pagine. Le 20 pagine supplementari completano un\u2019esposizione concisa dei fatti, delle doglianze e delle informazioni relative al rispetto dei criteri di ricevibilit\u00e0, la quale deve figurare nelle rubriche pertinenti del formulario di ricorso. Non \u00e8 peraltro possibile aggiungere delle nuove doglianze nell\u2019allegato, il quale deve servire esclusivamente a sviluppare le doglianze gi\u00e0 sollevate nel formulario di ricorso stesso.<\/p>\r\n<p>Si noti che, qualora un caso venga comunicato al governo convenuto per sollecitare le sue osservazioni, il ricorrente \u00e8 invitato a rispondere in maniera dettagliata.<\/p>\r\n<p>Tutte le osservazioni devono <strong>essere perfettamente leggibili<\/strong>. Qualora dovessero essere allegate delle osservazioni complementari, oltre all\u2019esposizione dei fatti, alle doglianze e alle informazioni relative al rispetto dei criteri di ricevibilit\u00e0 presenti nel formulario, esse dovranno: <\/p>\r\n<ul class=\"ec-guidance-list\">\r\n\t<li>se dattilografate, essere redatte con carattere non inferiore a 12 nel corpo del testo e 10 nelle note in calce,<\/li>\r\n\t<li>nel caso di allegati, utilizzare il formato A4 e prevedere un margine di almeno 3,5 cm in larghezza,<\/li>\r\n\t<li>essere numerate in modo consecutivo e<\/li>\r\n\t<li>essere suddivise in paragrafi numerati.<\/li>\r\n<\/ul>\r\n<p>In linea di principio, tutte le informazioni contenute nel formulario di ricorso e i documenti trasmessi alla Cancelleria, incluse le informazioni relative al ricorrente o a terzi, sono <strong>accessibili al pubblico<\/strong>. Inoltre, tali informazioni potranno essere pubblicate in HUDOC, la banca dati della Corte accessibile via internet, qualora siano state integrate in un\u2019esposizione dei fatti preparata in vista della comunicazione del caso al governo convenuto, in una decisione sulla ricevibilit\u00e0, in una decisione di cancellazione dal ruolo o in una sentenza. Di conseguenza, il ricorrente \u00e8 invitato a fornire unicamente informazioni sulla sua vita privata o quella di terzi essenziali alla comprensione del caso.<\/p>\r\n<p>Il ricorrente che non desideri che la sua identit\u00e0 venga rivelata, deve precisarlo e fornire le ragioni che giustifichino una deroga alla regola normale di pubblicit\u00e0 della procedura. La Corte pu\u00f2 autorizzare <strong>l\u2019anonimato<\/strong> in casi eccezionali e debitamente motivati.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-2 su-spoiler-closed\" data-anchor=\"sezione-e\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h4>E. Esposizione dei fatti<\/h4><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p><strong>58\u201360.<\/strong> Utilizzare uno stile chiaro e conciso. Indicare delle date esatte.<\/p>\r\n<p>Presentare i fatti in ordine cronologico: esporre le vicende nell\u2019ordine in cui si sono svolte.<\/p>\r\n<p>Se le doglianze riguardano questioni diverse (ad esempio procedimenti giudiziari diversi), ogni singola questione di fatto dovr\u00e0 essere presentata separatamente.<\/p>\r\n<p>Il ricorrente deve fornire documentazione a sostegno delle proprie argomentazioni, in particolare copia delle decisioni rilevanti e dei documenti riguardanti i provvedimenti di cui si lamenta, ad esempio un decreto di espulsione o una decisione di allontanamento. Dovr\u00e0 altres\u00ec fornire la documentazione a sostegno delle singole doglianze (referti medici, testimonianze, trascrizioni, titoli di propriet\u00e0, rapporti di detenzione, ecc.). Nel caso risulti impossibile ottenere copia di alcuni documenti, \u00e8 necessario indicarne le ragioni.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-2 su-spoiler-closed\" data-anchor=\"sezione-f\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h4>F. Esposizione della\/e violazione\/i della Convenzione e\/o dei Protocolli lamentate, nonch\u00e9 delle relative argomentazioni<\/h4><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p><strong>61\u201362.<\/strong> Per ogni doglianza, sar\u00e0 ncessario precisare l\u2019articolo della Convenzione o dei suoi Protocolli invocato e spiegare brevemente in che termini tale disposizione sia stata violata.<\/p>\r\n<p>\u00c8 altres\u00ec necessario spiegare, nella maniera pi\u00f9 precisa possibile, qual \u00e8 la doglianza rispetto alla Convenzione, indicando la disposizione della Convenzione invocata e spiegando in che termini i fatti esposti violino tale disposizione. Quanto precede vale per ognuna delle doglianze formulate.<\/p>\r\n<p><strong>Esempio:<\/strong><\/p>\r\n<p class=\"u-indent-1\"><em>Articolo 6 \u00a7 1: la procedura civile relativa alla mia richiesta di indennizzo \u00e8 stata eccessivamente lunga poich\u00e9 \u00e8 durata oltre dieci anni, dal 10 gennaio 2002 al 25 aprile 2012.<\/em><\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-2 su-spoiler-closed\" data-anchor=\"sezione-g\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h4>G. Rispetto dei criteri di ricevibilit\u00e0 enunciati all\u2019articolo 35 \u00a7 1 della Convenzione (Informazioni relative all\u2019esaurimento delle vie di ricorso interne e al rispetto del termine di quattro mesi)<\/h4><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p><strong>63.<\/strong> In questa sezione, il ricorrente deve dimostrare di aver dato allo Stato la possibilit\u00e0 di porre rimedio alla situazione lamentata prima di rivolgersi alla Corte: dovr\u00e0 quindi dar conto di aver esperito i ricorsi effettivi disponibili nel paese in questione.<\/p>\r\n<p>Per ognuna delle doglianze sollevate in virt\u00f9 della <a title=\"Convenzione per la salvaguardia dei Diritti dell\u2019Uomo e delle Libert\u00e0 fondamentali e suoi Protocolli\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/\">Convenzione o dei suoi Protocolli<\/a>, indicare:<\/p>\r\n<ul class=\"ec-guidance-list\">\r\n\t<li>la data esatta della decisione definitiva, il nome dell\u2019organo giurisdizionale e il tipo di decisione,<\/li>\r\n\t<li>le date delle decisioni degli organi giurisdizionali o istanze di grado inferiore che hanno condotto alla decisione definitiva, e<\/li>\r\n\t<li>il numero di riferimento del caso nella procedura interna.<\/li>\r\n<\/ul>\r\n<p>Deve essere allegata copia di tutte le decisioni rese dagli organi giurisdizionali o altre istanze, procedendo da quelli inferiori a quelli superiori. \u00c8 altres\u00ec necessario fornire copia delle istanze, domande giudiziali o ricorsi presentati davanti agli organi giurisdizionali, al fine di dimostrare di aver sollevato in sostanza, e a tutti i livelli, le doglianze in questione.<\/p>\r\n<p>Peraltro, il ricorrente dovr\u00e0 dimostrare che, per ognuna delle doglianze sollevate, la Corte viene adita nel termine di quattro mesi dalla rispettiva decisione interna definitiva. E\u2019 pertanto fondamentale la precisione nell\u2019indicazione delle date. A tale riguardo, \u00e8 necessario fornire prova di quanto precede, trasmettendo copia della decisione in cui figuri la data di emissione o di deposito. Qualora non sia stata ricevuta notizia della decisione definitiva il giorno in cui \u00e8 stata pronunciata o resa pubblica, dovr\u00e0 essere fornita prova della data in cui la stessa sia stata successivamente notificata, ad esempio una prova della data di ricevimento o una copia della lettera raccomandata o della busta. Nel caso in cui non esista alcun ricorso appropriato, il ricorrente dovr\u00e0 dimostrare di adire la Corte entro i quattro mesi dall\u2019atto, dalla misura o dalla decisione di cui si lamenta, fornendo prova documentale della data dell\u2019atto, della misura o della decisione.<\/p>\r\n<p><strong>64\u201365.<\/strong> Indicare se esisteva un ricorso disponibile non esperito, precisandone le ragioni.<\/p>\r\n<p>Ulteriori informazioni utili sull\u2019esaurimento delle vie di ricorso interne e sul rispetto del termine di quattro mesi, sono reperibili all\u2019interno della \u00ab<a href=\"https:\/\/www.echr.coe.int\/documents\/d\/echr\/admissibility_guide_ita\" target=\"_blank\" title=\"Guida pratica sulla ricevibilit\u00e0\" rel=\"noopener\">Guida pratica sulla ricevibilit\u00e0<\/a>\u00bb disponibile sul sito internet della Corte (www.echr.coe.int\/applicants).<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-2 su-spoiler-closed\" data-anchor=\"sezione-h\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h4>H. Informazioni relative alle altre istanze internazionali che stanno trattando o abbiano trattato la causa (se del caso)<\/h4><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p><strong>66\u201367.<\/strong> Il ricorrente dovr\u00e0 indicare se le doglianze formulate nel suo ricorso siano gi\u00e0 state sottoposte ad un\u2019altra istanza internazionale di inchiesta o di risoluzione, ad esempio un organismo delle Nazioni Unite quali l\u2019OIL o il Comitato dei diritti dell\u2019uomo delle Nazioni Unite, oppure una commissione internazionale di arbitrato. In caso affermativo, dovr\u00e0 in particolare precisare di quale istanza si tratta, indicando date e dettagli di ogni procedura eventualmente condotta e delle relative decisioni adottate e fornendo copia di tali decisioni e di qualsiasi documento pertinente.<\/p>\r\n<p><strong>68\u201369.<\/strong> Ricorsi precedentemente introdotti dinanzi alla Corte (casi chiusi o pendenti): \u00e8 necessario indicare se il ricorrente ha gi\u00e0 adito la Corte in precedenza, precisando, in caso affermativo, il\/i numero\/i di ricorso. Tali informazioni sono indispensabili per consentire alla Corte di classificare, ritrovare e trattare i diversi ricorsi introdotti a nome di uno stesso ricorrente.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-2 su-spoiler-closed\" data-anchor=\"sezione-i-elenco-dei-documenti-allegati\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h4>I. Elenco dei documenti allegati<\/h4><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p><strong>70.<\/strong> Dovr\u00e0 essere allegato un elenco numerato e cronologico di tutte le decisioni giudiziarie menzionate alle sezioni E, F, G e H del <a href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/formulario-di-ricorso\/\" title=\"Formulario di ricorso alla Corte europea dei diritti dell\u2019uomo\">formulario di ricorso<\/a>, nonch\u00e9 qualsiasi altro documento che Lei ritenga debba essere sottoposto all\u2019attenzione della Corte quale elemento comprovante le violazioni della <a title=\"Convenzione per la salvaguardia dei Diritti dell\u2019Uomo e delle Libert\u00e0 fondamentali\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/convenzione-europea-dei-diritti-delluomo\/\">Convenzione<\/a> lamentate (trascrizioni, testimonianze, referti medici, ecc.). Indicare nell\u2019elenco dei documenti il numero di pagina corrispondente ad ogni documento in modo che la Corte possa individuarli facilmente. Nel caso in cui lo spazio del formulario di ricorso a ci[\u00f2] previsto non fosse sufficiente, sar\u00e0 possibile aggiungere un foglio supplementare.<\/p>\r\n<p>Dovranno essere allegate copie complete e leggibili di tutti i documenti.<\/p>\r\n<p><strong>Nessun documento verr\u00e0 restituito. \u00c8 quindi nell\u2019interesse del ricorrente trasmettere delle copie e non gli originali.<\/strong><\/p>\r\n<p>\u00c8 FONDAMENTALE:<\/p>\r\n<ul class=\"ec-guidance-list\">\t\r\n\t<li>classificare i documenti in ordine cronologico e per procedimento,<\/li>\r\n\t<li>numerare le pagine in ordine consecutivo, e<\/li>\r\n\t<li>NON spillare, rilegare o incollare con nastro adesivo i documenti.<\/li>\r\n<\/ul>\r\n<p><strong>NB:<\/strong> spetta al ricorrente agire tempestivamente per ottenere le informazioni e i documenti necessari per la presentazione di un ricorso completo. Nel caso in cui dovesse mancare uno o pi\u00f9 di tali documenti, il ricorso non sar\u00e0 considerato completo e non verr\u00e0 esaminato dalla Corte, salvo che venga fornita una spiegazione esauriente del motivo per cui non \u00e8 stato possibile fornire i documenti mancanti.<\/p>\r\n<p class=\"ec-doc-callout\">Si noti che, per ragioni di sicurezza, i ricorsi contenenti oggetti sospetti verranno distrutti.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-2 su-spoiler-closed\" data-anchor=\"dichiarazione-e-firma\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h4>Dichiarazione e firma<\/h4><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>Questa sezione deve contenere delle firme originali.<\/p>\r\n<p><strong>72\u201373.<\/strong> La dichiarazione deve essere firmata da ognuno dei ricorrenti o dal rappresentante delegato dagli stessi. Nessuna altra persona \u00e8 legittimata a firmarla.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-2 su-spoiler-closed\" data-anchor=\"corrispondente\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h4>Designazione del corrispondente<\/h4><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p><strong>74.<\/strong> La Cancelleria corrisponder\u00e0 unicamente con <strong>un<\/strong> ricorrente o <strong>un<\/strong> rappresentante. Nel caso in cui vi siano diversi ricorrenti che non abbiano nominato nessun rappresentante, sar\u00e0 necessario designare uno di essi come corrispondente. Nel caso in cui il ricorrente sia rappresentato, la Cancelleria corrisponder\u00e0 con un solo rappresentante. Cos\u00ec, ad esempio, un ricorrente rappresentato da pi\u00f9 avvocati dovr\u00e0 indicare il nome di colui il quale corrisponder\u00e0 con la Corte.<\/p><\/div><\/div>\r\r\n<h2 class=\"su-spoiler-title ec-fake-spoiler-heading\" id=\"iii\">III. Introduzione e trattamento del ricorso<\/h2>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-1 su-spoiler-closed\" data-anchor=\"iii-a\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>A. Modalit\u00e0 d\u2019introduzione di un ricorso<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>La Corte pu\u00f2 essere adita unicamente per via postale (e non per telefono). Ci\u00f2 significa che la versione cartacea del <a href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/formulario-di-ricorso\/\" title=\"Formulario di ricorso alla Corte europea dei diritti dell\u2019uomo\">formulario di ricorso<\/a> recante la firma originale del o dei ricorrenti e\/o del o dei rappresentanti autorizzati dovr\u00e0 essere inviata per posta. Un ricorso inviato semplicemente via fax non sar\u00e0 considerato completo; la Corte deve ricevere l\u2019originale firmato del formulario di ricorso. <strong>\u00c8 inutile recarsi di persona a Strasburgo per esporre il proprio caso oralmente.<\/strong><\/p>\r\n<p>\u00c8 possibile scaricare il <a href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/formulario-di-ricorso\/\" title=\"Formulario di ricorso alla Corte europea dei diritti dell\u2019uomo\">formulario di ricorso<\/a> dal sito internet della Corte (www.echr.coe.int\/applicants).<\/p>\r\n<p><strong>Il formulario di ricorso deve essere inviato all\u2019indirizzo seguente:<\/p>\r\n<p class=\"u-indent-1\">The Registrar<br>\r\nEuropean Court of Human Rights<br>\r\nCouncil of Europe<br>\r\n67075 STRASBOURG CEDEX<br>\r\nFRANCE<\/strong><\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-1 su-spoiler-closed\" data-anchor=\"iii-b\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>B. Trattamento del ricorso<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>Il fascicolo relativo ad un ricorso viene aperto e integrato con le lettere e i documenti inviati alla Corte soltanto al ricevimento di un <a href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/formulario-di-ricorso\/\" title=\"Formulario di ricorso alla Corte europea dei diritti dell\u2019uomo\">formulario di ricorso<\/a> completo corredato di tutti i documenti richiesti.<\/p>\r\n<p>All\u2019atto del ricevimento di un formulario di ricorso, la Cancelleria della Corte verifica che esso contenga tutte le informazioni e tutti i documenti necessari. In caso contrario, il ricorrente ricever\u00e0 una risposta con la quale verr\u00e0 informato del fatto che a causa del mancato rispetto dei requisiti di cui all\u2019<a title=\"Articolo 47 del Regolamento della Corte Europea dei Diritti dell\u2019Uomo\" href=\"https:\/\/europeancourt.org\/it\/documenti\/consiglio-deuropa\/cedu\/regolamento-articolo-47\/\">articolo 47 del Regolamento<\/a>, non \u00e8 stato aperto un fascicolo e i documenti inviati non sono stati conservati. In tal caso il ricorrente ha la possibilit\u00e0 di introdurre un nuovo ricorso inviando un formulario di ricorso completo e corredato di tutti i documenti e le decisioni pertinenti, comprese le informazioni gi\u00e0 inviate la prima volta. I ricorsi incompleti non verranno accettati.<\/p>\r\n<p>La Cancelleria non pu\u00f2 fornire informazioni sul diritto e le leggi dello Stato contro il quale la parte ricorrente si lamenta, n\u00e9 fornire consulenza giuridica riguardo l\u2019applicazione e l\u2019interpretazione del diritto nazionale.<\/p>\r\n<p>Al momento dell\u2019invio di un ricorso alla Corte, conservare sempre una copia del formulario compilato nonch\u00e9 dei documenti originali. In tal modo, qualora la Cancelleria dovesse ritenere che il ricorso \u00e8 incompleto, sar\u00e0 pi\u00f9 facile introdurre un nuovo ricorso completo nel pi\u00f9 breve tempo possibile. Non vi \u00e8 nessuna garanzia che, nel caso in cui un ricorso venga considerato incompleto, il ricorrente abbia tempo sufficiente per introdurne uno nuovo prima della scadenza del termine dei quattro mesi. \u00c8 pertanto importante inviare un ricorso completo con tutti i documenti necessari in tempo utile.<\/p>\r\n<p>Quando viene inviato un ricorso completo, la Cancelleria potrebbe inviare una risposta nella quale si informa la parte ricorrente dell\u2019apertura di <strong>un fascicolo a suo nome (il cui numero dovr\u00e0 essere menzionato in tutta la corrispondenza futura)<\/strong>, nonch\u00e9 delle etichette recanti un codice a barre da utilizzare in tutta la corrispondenza successiva.<\/p>\r\n<p>\u00c8 altres\u00ec possibile che la Cancelleria richieda ulteriori informazioni o chiarimenti. \u00c8 nell\u2019interesse della parte ricorrente rispondere rapidamente alle lettere della Corte poich\u00e9 i nuovi fascicoli che rimangono inattivi per un tempo superiore a sei mesi vengono distrutti. Inoltre, quando un caso \u00e8 pronto a essere esaminato dalla Corte, un semplice ritardo o una mancata risposta alle lettere della Cancelleria, o la mancata comunicazione delle informazioni e dei documenti richiesti, rischiano di essere considerati come una manifestazione di disinteresse a proseguire l\u2019istruzione del fascicolo, con la conseguenza che la Corte potrebbe decidere di non esaminare il ricorso, di dichiararlo irricevibile o di cancellarlo dal ruolo.<\/p><\/div><\/div>\r\r\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus h-toaccordion includetocloseall padding-left-level-1 su-spoiler-closed\" data-anchor=\"iii-c\" data-scroll-offset=\"50\" data-anchor-in-url=\"yes\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span><h3>C. Gratuit\u00e0 della procedura<\/h3><\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\r\r\n<p>L\u2019istruzione del fascicolo \u00e8 <strong>gratuita<\/strong>. La parte ricorrente verr\u00e0 sistematicamente informata di ogni decisione adottata dalla Corte.<\/p><\/div><\/div>\r\r\n<\/div>","protected":false},"excerpt":{"rendered":"ITA \u2013 2026\/1 Espandi tutto Comprimi tutto","protected":false},"author":1,"featured_media":237635,"parent":176232,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-147731","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/europeancourt.org\/it\/wp-json\/wp\/v2\/pages\/147731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europeancourt.org\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/europeancourt.org\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/europeancourt.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/europeancourt.org\/it\/wp-json\/wp\/v2\/comments?post=147731"}],"version-history":[{"count":0,"href":"https:\/\/europeancourt.org\/it\/wp-json\/wp\/v2\/pages\/147731\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/europeancourt.org\/it\/wp-json\/wp\/v2\/pages\/176232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europeancourt.org\/it\/wp-json\/wp\/v2\/media\/237635"}],"wp:attachment":[{"href":"https:\/\/europeancourt.org\/it\/wp-json\/wp\/v2\/media?parent=147731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europeancourt.org\/it\/wp-json\/wp\/v2\/categories?post=147731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europeancourt.org\/it\/wp-json\/wp\/v2\/tags?post=147731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}